{"id":1198,"date":"2023-10-25T11:29:04","date_gmt":"2023-10-25T14:29:04","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=1198"},"modified":"2023-10-25T11:29:04","modified_gmt":"2023-10-25T14:29:04","slug":"primeira-edicao-da-feira-no-entorno-tem-brilha-no-distrito-federal","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2023\/10\/25\/primeira-edicao-da-feira-no-entorno-tem-brilha-no-distrito-federal\/","title":{"rendered":"Primeira Edi\u00e7\u00e3o da Feira &#8216;No Entorno Tem&#8217; Brilha no Distrito Federal"},"content":{"rendered":"<p>No \u00faltimo fim de semana, 21 e 22 de outubro, o Entorno do Distrito Federal ganhou destaque ao apresentar suas potencialidades. A primeira edi\u00e7\u00e3o da feira &#8220;No Entorno Tem&#8221; foi um verdadeiro sucesso, com a abertura oficial ocorrendo no s\u00e1bado, 21 de outubro, e a honrosa presen\u00e7a do Governador de Goi\u00e1s, Ronaldo Caiado.<\/p>\n<p>O Parque da Cidade tornou-se o palco para Valpara\u00edso de Goi\u00e1s e outros 12 munic\u00edpios, ricos em turismo de aventura, neg\u00f3cios, artesanato, gastronomia e religiosidade, mostrarem seus atrativos e apresentarem o que cada cidade tem de melhor.<\/p>\n<p>O prefeito P\u00e1bio Mossor\u00f3 expressou sua gratid\u00e3o: &#8220;Agrade\u00e7o ao governador Ronaldo Caiado por ter esse olhar especial para nossa regi\u00e3o e \u00e0 Secret\u00e1ria Carol Fleury, pelo empenho nesse trabalho. Gratid\u00e3o tamb\u00e9m aos vereadores, equipe de governo e \u00e0 deputada Zeli.&#8221;<\/p>\n<p>No espa\u00e7o dedicado a Valpara\u00edso, promovido pela Secretaria de Desenvolvimento Econ\u00f4mico de Trabalho, os representantes puderam exibir a riqueza da cidade em termos de lazer, belezas naturais, artesanato, agricultura familiar e o potencial do turismo.<\/p>\n<p>A secret\u00e1ria do Entorno, Carol Fleury, destacou a import\u00e2ncia do evento: &#8220;Esse evento \u00e9 muito significativo, pois nos d\u00e1 a oportunidade de divulgar a voca\u00e7\u00e3o de cada munic\u00edpio. Bras\u00edlia est\u00e1 t\u00e3o pr\u00f3xima de n\u00f3s, e muitas vezes n\u00e3o conhece nossas riquezas. As pessoas sair\u00e3o daqui encantadas, conhecendo o melhor que temos a oferecer e ansiosas para explorar ainda mais.&#8221;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo fim de semana, 21 e 22 de outubro, o Entorno do Distrito Federal ganhou destaque ao apresentar suas potencialidades. A primeira edi\u00e7\u00e3o da feira &#8220;No Entorno Tem&#8221; foi um verdadeiro sucesso, com a abertura oficial ocorrendo no s\u00e1bado, 21 de outubro, e a honrosa presen\u00e7a do Governador de Goi\u00e1s, Ronaldo Caiado. O Parque [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1199,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[21],"tags":[],"class_list":["post-1198","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governo","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1198","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1198"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1198\/revisions"}],"predecessor-version":[{"id":1200,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1198\/revisions\/1200"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/1199"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1198"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1198"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1198"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}