{"id":1451,"date":"2023-11-30T10:01:20","date_gmt":"2023-11-30T12:01:20","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=1451"},"modified":"2023-11-30T10:01:20","modified_gmt":"2023-11-30T12:01:20","slug":"a-camara-municipal-de-luziania-renova-seu-compromisso-com-a-comunidade-evangelica-ao-entregar-medalha-de-honra-ao-merito","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2023\/11\/30\/a-camara-municipal-de-luziania-renova-seu-compromisso-com-a-comunidade-evangelica-ao-entregar-medalha-de-honra-ao-merito\/","title":{"rendered":"A C\u00e2mara Municipal de Luzi\u00e2nia Renova seu Compromisso com a Comunidade Evang\u00e9lica ao Entregar Medalha de Honra ao M\u00e9rito"},"content":{"rendered":"<p>Na marcante Sess\u00e3o Solene desta ter\u00e7a-feira (28\/11), a C\u00e2mara Municipal de Luzi\u00e2nia reafirmou seu compromisso e reconhecimento \u00e0 comunidade evang\u00e9lica, dedicando uma cerim\u00f4nia especial em homenagem ao seu dia. A entrega da Medalha de Honra ao M\u00e9rito Gunnar Vingren e Daniel Berg foi um gesto significativo de apre\u00e7o pelos l\u00edderes e membros das igrejas evang\u00e9licas locais, um reconhecimento merecido pelo papel fundamental que desempenham na vida da comunidade.<\/p>\n<p>O vereador Paulinho Cabeleireiro, autor do Projeto de Lei que culminou na Resolu\u00e7\u00e3o n\u00ba 627, expressou sua admira\u00e7\u00e3o pela miss\u00e3o das igrejas, destacando-as como elementos vitais para a sociedade. Durante sua fala, ressaltou a import\u00e2ncia das ora\u00e7\u00f5es, prega\u00e7\u00f5es e aconselhamento pastoral, que n\u00e3o apenas fortalecem a espiritualidade, mas tamb\u00e9m desempenham um papel crucial no acolhimento das pessoas. O vereador agradeceu ao prefeito Diego Sorgatto por seu apoio e reconhecimento \u00e0 relev\u00e2ncia dos evang\u00e9licos no munic\u00edpio.<\/p>\n<p>O Pastor Valdomiro Francisco Marques, ao receber a homenagem, real\u00e7ou a essencialidade da evangeliza\u00e7\u00e3o e o impacto positivo na restaura\u00e7\u00e3o de fam\u00edlias, especialmente aquelas que enfrentam desafios sociais. Ele enfatizou que Luzi\u00e2nia \u00e9 verdadeiramente aben\u00e7oada por ter uma multiplicidade de igrejas dedicadas a pregar a palavra e servir \u00e0 comunidade.<\/p>\n<p>A cerim\u00f4nia, conduzida com respeito e solenidade, viu cada vereador apresentar a biografia do homenageado e entregar a Medalha de Honra ao M\u00e9rito, proporcionando um momento \u00edntimo de reconhecimento e celebra\u00e7\u00e3o. O evento contou ainda com a participa\u00e7\u00e3o especial de Amanda de Paula, que trouxe louvores que ecoaram pelos corredores da C\u00e2mara Municipal.<\/p>\n<p>Ao promover e celebrar ativamente as contribui\u00e7\u00f5es valiosas das comunidades importantes para o munic\u00edpio, a C\u00e2mara Municipal de Luzi\u00e2nia refor\u00e7a seu compromisso com a diversidade e a riqueza cultural, religiosa e social que fazem de Luzi\u00e2nia uma comunidade vibrante e inclusiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na marcante Sess\u00e3o Solene desta ter\u00e7a-feira (28\/11), a C\u00e2mara Municipal de Luzi\u00e2nia reafirmou seu compromisso e reconhecimento \u00e0 comunidade evang\u00e9lica, dedicando uma cerim\u00f4nia especial em homenagem ao seu dia. A entrega da Medalha de Honra ao M\u00e9rito Gunnar Vingren e Daniel Berg foi um gesto significativo de apre\u00e7o pelos l\u00edderes e membros das igrejas evang\u00e9licas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1452,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-1451","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1451","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1451"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1451\/revisions"}],"predecessor-version":[{"id":1453,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/1451\/revisions\/1453"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/1452"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1451"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=1451"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=1451"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}