{"id":3074,"date":"2024-06-15T09:17:09","date_gmt":"2024-06-15T12:17:09","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=3074"},"modified":"2024-06-15T09:17:09","modified_gmt":"2024-06-15T12:17:09","slug":"segunda-noite-do-valparaiso-rodeio-show-encanta-multidao-com-show-de-amado-batista","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2024\/06\/15\/segunda-noite-do-valparaiso-rodeio-show-encanta-multidao-com-show-de-amado-batista\/","title":{"rendered":"SEGUNDA NOITE DO VALPARA\u00cdSO RODEIO SHOW ENCANTA MULTID\u00c3O COM SHOW DE AMADO BATISTA"},"content":{"rendered":"<p>A segunda noite do Valpara\u00edso Rodeio Show, em comemora\u00e7\u00e3o ao 29\u00ba anivers\u00e1rio de emancipa\u00e7\u00e3o pol\u00edtica de Valpara\u00edso de Goi\u00e1s, reuniu uma multid\u00e3o em uma noite repleta de emo\u00e7\u00f5es e m\u00fasica de qualidade. O evento, que j\u00e1 \u00e9 uma tradi\u00e7\u00e3o na cidade, contou com a presen\u00e7a ilustre do cantor Amado Batista, que emocionou o p\u00fablico ao apresentar seus maiores sucessos, como &#8220;Folha Seca&#8221;, &#8220;Princesa&#8221;, &#8220;Meu Ex-Amor&#8221;, &#8220;Secret\u00e1ria&#8221; e &#8220;Seresteiro Das Noites&#8221;.<\/p>\n<p>Al\u00e9m de Amado Batista, a noite foi abrilhantada pelas apresenta\u00e7\u00f5es do talentoso cantor local Igor Rafael e do carism\u00e1tico Erick Moral. Ambos subiram ao palco antes da estrela principal, aquecendo o p\u00fablico com suas performances envolventes.<\/p>\n<p>O rodeio, sob a condu\u00e7\u00e3o do renomado locutor Cuiabano Lima, trouxe competidores de diversos estados do Brasil, que mostraram suas habilidades nas montarias em touros, encantando e empolgando o p\u00fablico presente.<\/p>\n<p>\u201cA energia positiva, adrenalina e m\u00fasica de qualidade est\u00e3o garantidas em todas as noites do Valpara\u00edso Rodeio Show. Agrade\u00e7o a cada um que marcou presen\u00e7a e festejou conosco. Vale destacar que todos os artistas fizeram grandes apresenta\u00e7\u00f5es, conquistando a plateia e ficando marcados na mem\u00f3ria de todos os presentes nesta edi\u00e7\u00e3o da festan\u00e7a amada pelos valparaisenses\u201d, afirmou o prefeito P\u00e1bio Mossor\u00f3.<\/p>\n<p>O prefeito tamb\u00e9m destacou a import\u00e2ncia do evento para a comunidade: \u201cNovamente, vivenciamos momentos especiais, de divers\u00e3o e alegria para toda a popula\u00e7\u00e3o de Valpara\u00edso e cidades vizinhas. O p\u00fablico elogiou bastante a festa e entendeu a ess\u00eancia de comemorar o 29\u00ba anivers\u00e1rio de emancipa\u00e7\u00e3o pol\u00edtico-administrativa do munic\u00edpio em grande estilo e com um evento bem organizado. Convido a todos para comparecer \u00e0 arena at\u00e9 domingo. Teremos muitas noites inesquec\u00edveis\u201d, concluiu Mossor\u00f3.<\/p>\n<p>Organizado pelo Governo de Valpara\u00edso de Goi\u00e1s, por meio das secretarias de Cultura e Esporte (SMCE) e de Finan\u00e7as e Planejamento, o Valpara\u00edso Rodeio Show acontece no Parque Esplanada III, atraindo milhares de pessoas de Valpara\u00edso, munic\u00edpios vizinhos de Goi\u00e1s e do Distrito Federal. A entrada \u00e9 gratuita, assim como todas as atra\u00e7\u00f5es musicais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A segunda noite do Valpara\u00edso Rodeio Show, em comemora\u00e7\u00e3o ao 29\u00ba anivers\u00e1rio de emancipa\u00e7\u00e3o pol\u00edtica de Valpara\u00edso de Goi\u00e1s, reuniu uma multid\u00e3o em uma noite repleta de emo\u00e7\u00f5es e m\u00fasica de qualidade. O evento, que j\u00e1 \u00e9 uma tradi\u00e7\u00e3o na cidade, contou com a presen\u00e7a ilustre do cantor Amado Batista, que emocionou o p\u00fablico ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3075,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-3074","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3074"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3074\/revisions"}],"predecessor-version":[{"id":3076,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3074\/revisions\/3076"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/3075"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}