{"id":3538,"date":"2024-10-01T10:12:35","date_gmt":"2024-10-01T13:12:35","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=3538"},"modified":"2024-10-01T10:14:29","modified_gmt":"2024-10-01T13:14:29","slug":"eleicoes-em-luziania-devem-custar-cerca-de-r-4-milhoes-aos-cofres-publicos-saiba-quanto-cada-candidato-recebeu-ate-agora","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2024\/10\/01\/eleicoes-em-luziania-devem-custar-cerca-de-r-4-milhoes-aos-cofres-publicos-saiba-quanto-cada-candidato-recebeu-ate-agora\/","title":{"rendered":"Elei\u00e7\u00f5es em Luzi\u00e2nia Devem Custar Cerca de R$ 4 Milh\u00f5es aos Cofres P\u00fablicos \u2014 Saiba Quanto Cada Candidato Recebeu At\u00e9 Agora"},"content":{"rendered":"<p>As <strong>elei\u00e7\u00f5es em Luzi\u00e2nia<\/strong> devem gerar um custo de aproximadamente <strong>R$ 4 milh\u00f5es em recursos p\u00fablicos<\/strong>, destinados ao financiamento das campanhas dos principais candidatos. Os valores informados pelo Tribunal Superior Eleitoral (TSE), por meio do aplicativo <strong>DivulgaCand<\/strong>, ainda podem sofrer altera\u00e7\u00f5es, uma vez que os candidatos podem continuar recebendo recursos dos fundos eleitoral e partid\u00e1rio at\u00e9 o fim do pleito.<\/p>\n<h3><\/h3>\n<h3>Ana L\u00facia \u00e9 a Candidata com Maior Financiamento<\/h3>\n<p>A ex-vereadora <strong>Ana L\u00facia<\/strong>, do PSDB, foi a candidata que mais recebeu recursos at\u00e9 o momento. O partido repassou para sua campanha o montante de <strong>R$ 1.450.000,00<\/strong>, sendo que desse total, a tucana j\u00e1 gastou <strong>R$ 963 mil<\/strong>. Com esse valor, Ana L\u00facia lidera entre os candidatos no que diz respeito ao financiamento p\u00fablico para as elei\u00e7\u00f5es de Luzi\u00e2nia.<\/p>\n<p>Na segunda posi\u00e7\u00e3o em termos de financiamento est\u00e1 o candidato <strong>Waltinho<\/strong>, do PL, que recebeu <strong>R$ 1,4 milh\u00e3o<\/strong> do fundo partid\u00e1rio. At\u00e9 o momento, ele declarou gastos de <strong>R$ 585 mil<\/strong> em sua campanha.<\/p>\n<h3><\/h3>\n<h3>Prefeito Diego Sorgatto J\u00e1 Gastou Mais do Que Recebeu<\/h3>\n<p>O atual prefeito e candidato \u00e0 reelei\u00e7\u00e3o, <strong>Diego Sorgatto<\/strong>, do Uni\u00e3o Brasil, est\u00e1 em uma situa\u00e7\u00e3o diferente. At\u00e9 agora, ele recebeu <strong>R$ 300 mil<\/strong> para sua campanha, mas j\u00e1 empenhou <strong>R$ 865 mil<\/strong> em gastos. Do valor recebido, <strong>R$ 195 mil<\/strong> foram provenientes do pr\u00f3prio partido. A discrep\u00e2ncia entre o que foi recebido e o que foi gasto pode ser explicada por doa\u00e7\u00f5es de outras fontes ou fundos pr\u00f3prios ainda n\u00e3o detalhados.<\/p>\n<p>O candidato <strong>Lee Almeida<\/strong>, do PSOL, n\u00e3o recebeu recursos p\u00fablicos para financiar sua campanha, em raz\u00e3o da cl\u00e1usula de desempenho que afeta o partido. Al\u00e9m disso, ele n\u00e3o declarou at\u00e9 o momento doa\u00e7\u00f5es de outras fontes, o que o coloca em desvantagem financeira em rela\u00e7\u00e3o aos demais concorrentes.<\/p>\n<h3><\/h3>\n<h3>Devolu\u00e7\u00e3o de Recursos N\u00e3o Utilizados<\/h3>\n<p>\u00c9 importante lembrar que, conforme a legisla\u00e7\u00e3o eleitoral, os candidatos s\u00e3o obrigados a devolver aos cofres p\u00fablicos qualquer recurso que n\u00e3o for utilizado durante a campanha.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>As elei\u00e7\u00f5es em Luzi\u00e2nia devem gerar um custo de aproximadamente R$ 4 milh\u00f5es em recursos p\u00fablicos, destinados ao financiamento das campanhas dos principais candidatos. Os valores informados pelo Tribunal Superior Eleitoral (TSE), por meio do aplicativo DivulgaCand, ainda podem sofrer altera\u00e7\u00f5es, uma vez que os candidatos podem continuar recebendo recursos dos fundos eleitoral e partid\u00e1rio [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-3538","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3538","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3538"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3538\/revisions"}],"predecessor-version":[{"id":3540,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3538\/revisions\/3540"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/3539"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3538"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3538"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3538"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}