{"id":3616,"date":"2024-10-10T10:05:20","date_gmt":"2024-10-10T13:05:20","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=3616"},"modified":"2024-10-10T10:05:20","modified_gmt":"2024-10-10T13:05:20","slug":"pt-enfrenta-desafios-e-fica-sem-representantes-na-camara-de-valparaiso-de-goias","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2024\/10\/10\/pt-enfrenta-desafios-e-fica-sem-representantes-na-camara-de-valparaiso-de-goias\/","title":{"rendered":"PT enfrenta desafios e fica sem representantes na C\u00e2mara de Valpara\u00edso de Goi\u00e1s"},"content":{"rendered":"<p>Mesmo sem conquistar cadeiras no <strong>Legislativo de Valpara\u00edso de Goi\u00e1s<\/strong>, o <strong>Partido dos Trabalhadores (PT)<\/strong> considera que a campanha teve resultados positivos. Segundo <strong>Berilo Le\u00e3o<\/strong>, presidente do PT na cidade e ex-candidato a vereador nas elei\u00e7\u00f5es de 2024, o partido enfrentou uma disputa dif\u00edcil, mas trouxe aprendizados e fortaleceu a legenda local.<\/p>\n<p>Apesar dos desafios, a esposa de Berilo, <strong>Lucimar Nascimento<\/strong>, que concorreu ao cargo de prefeita, obteve <strong>2.781 votos<\/strong>, ficando em quarto lugar na disputa majorit\u00e1ria. J\u00e1 o <strong>Professor Silvano<\/strong>, outro nome importante da legenda, obteve <strong>580 votos<\/strong> para vereador, mas n\u00e3o conseguiu uma vaga na C\u00e2mara Municipal.<\/p>\n<p>Segundo Berilo, a campanha do PT enfrentou a concorr\u00eancia de grupos pol\u00edticos mais robustos financeiramente, como o do atual prefeito, <strong>P\u00e1bio Mossor\u00f3 (MDB)<\/strong>, e o da deputada <strong>L\u00eada Borges (PSDB)<\/strong>. Mesmo assim, ele v\u00ea o saldo como positivo. &#8220;Foi um ato de coragem. Conhecemos muitas pessoas com potencial e isso ajuda a fortalecer a legenda&#8221;, destacou.<\/p>\n<p><strong>Professor Silvano<\/strong>, que tinha como um de seus projetos a volta do &#8220;Gabinete nas Ruas&#8221;, tamb\u00e9m avaliou o resultado de forma otimista e j\u00e1 est\u00e1 focado nas pr\u00f3ximas elei\u00e7\u00f5es. &#8220;Foi muito positivo. N\u00e3o vou desistir, e fico feliz com as pessoas que acreditaram em nossos projetos&#8221;, afirmou.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mesmo sem conquistar cadeiras no Legislativo de Valpara\u00edso de Goi\u00e1s, o Partido dos Trabalhadores (PT) considera que a campanha teve resultados positivos. Segundo Berilo Le\u00e3o, presidente do PT na cidade e ex-candidato a vereador nas elei\u00e7\u00f5es de 2024, o partido enfrentou uma disputa dif\u00edcil, mas trouxe aprendizados e fortaleceu a legenda local. Apesar dos desafios, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3617,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-3616","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3616","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3616"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3616\/revisions"}],"predecessor-version":[{"id":3618,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3616\/revisions\/3618"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/3617"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3616"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3616"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3616"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}