{"id":4368,"date":"2025-01-23T10:35:52","date_gmt":"2025-01-23T13:35:52","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4368"},"modified":"2025-01-23T10:35:52","modified_gmt":"2025-01-23T13:35:52","slug":"conselho-central-santa-luzia-de-luziania-torna-se-de-utilidade-publica","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/01\/23\/conselho-central-santa-luzia-de-luziania-torna-se-de-utilidade-publica\/","title":{"rendered":"Conselho Central Santa Luzia de Luzi\u00e2nia Torna-se de Utilidade P\u00fablica"},"content":{"rendered":"<p>O governador de Goi\u00e1s, <strong>Ronaldo Caiado<\/strong>, sancionou a <strong>Lei n.\u00ba 23.166<\/strong>, que reconhece como utilidade p\u00fablica o <strong>Conselho Central Santa Luzia de Luzi\u00e2nia<\/strong>, vinculado \u00e0 <strong>Sociedade de S\u00e3o Vicente de Paulo (SSVP)<\/strong>. A iniciativa \u2014 de autoria do deputado estadual <strong>Wilde Camb\u00e3o (PSD)<\/strong> \u2014 sublinha a relev\u00e2ncia social do Conselho, que h\u00e1 anos auxilia fam\u00edlias em situa\u00e7\u00e3o de vulnerabilidade no munic\u00edpio.<\/p>\n<h3><\/h3>\n<h3><strong>Amplia\u00e7\u00e3o das A\u00e7\u00f5es Sociais<\/strong><\/h3>\n<p>Com o novo status, o Conselho Central Santa Luzia passa a ter mais possibilidades de firmar <strong>parcerias<\/strong> e obter recursos que reforcem a oferta de servi\u00e7os comunit\u00e1rios. Representantes do \u00f3rg\u00e3o veem na san\u00e7\u00e3o um reconhecimento \u00e0 seriedade e \u00e0 efic\u00e1cia do trabalho, o que poder\u00e1 garantir maior sustenta\u00e7\u00e3o financeira e suporte a projetos de assist\u00eancia, inclus\u00e3o e cidadania.<\/p>\n<h3><\/h3>\n<h3><strong>Fortalecimento da Comunidade<\/strong><\/h3>\n<p>O projeto tamb\u00e9m reflete o compromisso do governo estadual e do Poder Legislativo goiano em <strong>valorizar entidades<\/strong> que promovem o bem-estar coletivo e atuam na constru\u00e7\u00e3o de uma sociedade mais justa. Segundo a SSVP, o aux\u00edlio concedido por meio dessa lei permitir\u00e1 ao Conselho desenvolver novas frentes de atendimento e consolidar as iniciativas j\u00e1 em curso, beneficiando diretamente a popula\u00e7\u00e3o de Luzi\u00e2nia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O governador de Goi\u00e1s, Ronaldo Caiado, sancionou a Lei n.\u00ba 23.166, que reconhece como utilidade p\u00fablica o Conselho Central Santa Luzia de Luzi\u00e2nia, vinculado \u00e0 Sociedade de S\u00e3o Vicente de Paulo (SSVP). A iniciativa \u2014 de autoria do deputado estadual Wilde Camb\u00e3o (PSD) \u2014 sublinha a relev\u00e2ncia social do Conselho, que h\u00e1 anos auxilia fam\u00edlias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4369,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-4368","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4368","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4368"}],"version-history":[{"count":2,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4368\/revisions"}],"predecessor-version":[{"id":4371,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4368\/revisions\/4371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4369"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4368"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4368"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4368"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}