{"id":4536,"date":"2025-02-13T10:01:34","date_gmt":"2025-02-13T13:01:34","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4536"},"modified":"2025-02-13T10:01:34","modified_gmt":"2025-02-13T13:01:34","slug":"reuniao-entre-prefeitos-e-governadores-do-df-e-de-goias-discute-preco-das-passagens-no-entorno","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/02\/13\/reuniao-entre-prefeitos-e-governadores-do-df-e-de-goias-discute-preco-das-passagens-no-entorno\/","title":{"rendered":"Reuni\u00e3o entre prefeitos e governadores do DF e de Goi\u00e1s discute pre\u00e7o das passagens no Entorno"},"content":{"rendered":"<p data-start=\"100\" data-end=\"413\">Uma nova reuni\u00e3o envolvendo o Governo de Goi\u00e1s, o Governo do Distrito Federal (GDF) e prefeitos de cidades do Entorno, a exemplo do chefe do Executivo Municipal de Valpara\u00edso, Marcus Vinicius, deve ocorrer em breve para tratar do poss\u00edvel reajuste das tarifas de \u00f4nibus que conectam a regi\u00e3o ao Distrito Federal.<\/p>\n<p data-start=\"415\" data-end=\"814\">O encontro foi anunciado durante a cerim\u00f4nia de recria\u00e7\u00e3o da Secretaria do Entorno do Distrito Federal, ocasi\u00e3o em que o governador Ibaneis Rocha destacou a relev\u00e2ncia de se encontrar uma solu\u00e7\u00e3o para as tarifas. \u201cA quest\u00e3o das passagens de \u00f4nibus do Entorno \u00e9 muito importante porque sacrifica a popula\u00e7\u00e3o local, mas tamb\u00e9m prejudica as empresas do DF que buscam m\u00e3o de obra\u201d, pontuou o governador.<\/p>\n<p data-start=\"816\" data-end=\"939\">Para o prefeito de Valpara\u00edso, Marcus Vinicius, o fortalecimento do di\u00e1logo com o Governo de Goi\u00e1s e o GDF \u00e9 fundamental:<\/p>\n<blockquote data-start=\"940\" data-end=\"1215\">\n<p data-start=\"942\" data-end=\"1215\">\u201cO futuro do DF e de Goi\u00e1s passa pelo Entorno. A recria\u00e7\u00e3o de uma secretaria exclusiva para a regi\u00e3o nos enche de expectativa para fazermos a diferen\u00e7a na vida da comunidade. Quanto mais pr\u00f3ximos os governos estadual e distrital, mais avan\u00e7amos\u201d, enfatizou Marcus Vinicius.<\/p>\n<\/blockquote>\n<p data-start=\"1217\" data-end=\"1563\">O rec\u00e9m-nomeado secret\u00e1rio do Entorno do DF, Cristian Viana, classificou o debate sobre a cria\u00e7\u00e3o de uma tarifa intermunicipal como o \u201cprincipal desafio\u201d de sua pasta, oficialmente criada na \u00faltima ter\u00e7a-feira (11). A meta \u00e9 melhorar a mobilidade e o acesso ao transporte p\u00fablico para quem transita diariamente entre o DF e as cidades do Entorno.<\/p>\n<h3 data-start=\"1565\" data-end=\"1595\"><\/h3>\n<h3 data-start=\"1565\" data-end=\"1595\"><strong data-start=\"1569\" data-end=\"1595\">Hist\u00f3rico de reajustes<\/strong><\/h3>\n<p data-start=\"1596\" data-end=\"1973\">Em fevereiro de 2024, a Ag\u00eancia Nacional de Transportes Terrestres (ANTT) j\u00e1 havia autorizado aumento m\u00e9dio de 8,56% nos valores das passagens, passando de R$ 4,45 a R$ 11,05. A medida foi justificada pela aus\u00eancia de reajuste durante 2021 e 2022, per\u00edodo em que a opera\u00e7\u00e3o no Entorno estava sob gest\u00e3o do GDF, o que teria dificultado as opera\u00e7\u00f5es das empresas de transporte.<\/p>\n<p data-start=\"1975\" data-end=\"2180\" data-is-last-node=\"\">A nova reuni\u00e3o busca, portanto, se antecipar a qualquer reajuste previsto para 2025, na tentativa de garantir um equil\u00edbrio que favore\u00e7a tanto a popula\u00e7\u00e3o do Entorno quanto as empresas de transporte do DF.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma nova reuni\u00e3o envolvendo o Governo de Goi\u00e1s, o Governo do Distrito Federal (GDF) e prefeitos de cidades do Entorno, a exemplo do chefe do Executivo Municipal de Valpara\u00edso, Marcus Vinicius, deve ocorrer em breve para tratar do poss\u00edvel reajuste das tarifas de \u00f4nibus que conectam a regi\u00e3o ao Distrito Federal. O encontro foi anunciado [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4537,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4536","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4536"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4536\/revisions"}],"predecessor-version":[{"id":4538,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4536\/revisions\/4538"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4537"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}