{"id":4539,"date":"2025-02-13T10:04:07","date_gmt":"2025-02-13T13:04:07","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4539"},"modified":"2025-02-13T10:04:07","modified_gmt":"2025-02-13T13:04:07","slug":"tarifa-zero-em-luziania-atinge-5-milhoes-de-viagens-e-cresce-355-desde-lancamento","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/02\/13\/tarifa-zero-em-luziania-atinge-5-milhoes-de-viagens-e-cresce-355-desde-lancamento\/","title":{"rendered":"Tarifa Zero em Luzi\u00e2nia atinge 5 milh\u00f5es de viagens e cresce 355% desde lan\u00e7amento"},"content":{"rendered":"<p data-start=\"88\" data-end=\"497\">O programa Tarifa Zero, que assegura gratuidade no transporte p\u00fablico municipal de Luzi\u00e2nia, alcan\u00e7ou a marca de 5 milh\u00f5es de passagens emitidas nesta ter\u00e7a-feira (11). Lan\u00e7ado em novembro de 2023 pelo prefeito Diego Sorgatto (UB), o servi\u00e7o registra crescimento de 355% no n\u00famero de passageiros ao longo de pouco mais de um ano de opera\u00e7\u00e3o, passando de 4,5 mil para 17 mil usu\u00e1rios transportados diariamente.<\/p>\n<p data-start=\"499\" data-end=\"925\">\n<p data-start=\"499\" data-end=\"925\"><strong data-start=\"499\" data-end=\"522\">Amplia\u00e7\u00e3o de linhas<\/strong><br data-start=\"522\" data-end=\"525\" \/>Para atender \u00e0 crescente demanda, a frota de \u00f4nibus do munic\u00edpio foi ampliada de 18 para 24 linhas, incluindo rotas na zona rural. Com isso, Luzi\u00e2nia se tornou a \u00fanica cidade do Entorno do Distrito Federal a oferecer transporte p\u00fablico totalmente gratuito, e a segunda em Goi\u00e1s a adotar essa iniciativa \u2014 antes, somente o pequeno munic\u00edpio de Anicuns havia adotado o sistema de Tarifa Zero no estado.<\/p>\n<p data-start=\"927\" data-end=\"1291\">\u201cO Tarifa Zero \u00e9 um marco na mobilidade urbana da nossa cidade. Atingir 5 milh\u00f5es de passagens em t\u00e3o pouco tempo comprova a import\u00e2ncia desse projeto para a popula\u00e7\u00e3o\u201d, ressalta o prefeito Diego Sorgatto. \u201cSeguimos trabalhando para avaliar e aperfei\u00e7oar o programa, de modo a garantir que mais pessoas usufruam de um transporte p\u00fablico de qualidade e sem custos.\u201d<\/p>\n<p data-start=\"1293\" data-end=\"1662\">\n<p data-start=\"1293\" data-end=\"1662\"><strong data-start=\"1293\" data-end=\"1311\">Economia local<\/strong><br data-start=\"1311\" data-end=\"1314\" \/>Segundo a Prefeitura, o programa impacta positivamente n\u00e3o apenas o deslocamento di\u00e1rio dos moradores, mas tamb\u00e9m a economia local. Desde sua implementa\u00e7\u00e3o, o com\u00e9rcio varejista de Luzi\u00e2nia registrou aumento de 36% e, no mesmo per\u00edodo, R$ 25 milh\u00f5es passaram a circular no com\u00e9rcio do munic\u00edpio \u2014 quantia que antes era gasta com tarifas de \u00f4nibus.<\/p>\n<p data-start=\"1664\" data-end=\"1884\">\u201cO recurso economizado na passagem volta em forma de consumo e servi\u00e7os, gerando emprego e renda para a popula\u00e7\u00e3o. \u00c9 um c\u00edrculo virtuoso que favorece o desenvolvimento econ\u00f4mico e social da cidade\u201d, explica o prefeito.<\/p>\n<p data-start=\"1886\" data-end=\"1975\">\n<p data-start=\"1886\" data-end=\"1975\"><strong data-start=\"1886\" data-end=\"1902\">Tr\u00eas pilares<\/strong><br data-start=\"1902\" data-end=\"1905\" \/>A iniciativa, de acordo com Diego Sorgatto, se baseia em tr\u00eas pilares:<\/p>\n<ul data-start=\"1977\" data-end=\"2361\">\n<li data-start=\"1977\" data-end=\"2088\"><strong data-start=\"1979\" data-end=\"1989\">Social<\/strong>: Garante a gratuidade das passagens para toda a popula\u00e7\u00e3o, ajudando sobretudo quem mais precisa.<\/li>\n<li data-start=\"2089\" data-end=\"2224\"><strong data-start=\"2091\" data-end=\"2104\">Econ\u00f4mico<\/strong>: Reduz custos de transporte para trabalhadores e empresas, aliviando a folha de pagamento e impulsionando o com\u00e9rcio.<\/li>\n<li data-start=\"2225\" data-end=\"2361\"><strong data-start=\"2227\" data-end=\"2240\">Ambiental<\/strong>: Contribui para a queda no n\u00famero de ve\u00edculos particulares em circula\u00e7\u00e3o, o que ajuda a diminuir a emiss\u00e3o de poluentes.<\/li>\n<\/ul>\n<p data-start=\"2363\" data-end=\"2819\" data-is-last-node=\"\">Com a proposta de acompanhar a evolu\u00e7\u00e3o da demanda, a Prefeitura avalia ampliar linhas e reestruturar o servi\u00e7o para assegurar a manuten\u00e7\u00e3o da qualidade e da sustentabilidade do programa. \u201cNosso compromisso \u00e9 seguir ajustando o Tarifa Zero para que ele continue suprindo as necessidades de mobilidade do povo luzi\u00e2niense, fortalecendo a economia local e mantendo Luzi\u00e2nia como refer\u00eancia em transporte p\u00fablico gratuito no Centro-Oeste\u201d, conclui o prefeito.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O programa Tarifa Zero, que assegura gratuidade no transporte p\u00fablico municipal de Luzi\u00e2nia, alcan\u00e7ou a marca de 5 milh\u00f5es de passagens emitidas nesta ter\u00e7a-feira (11). Lan\u00e7ado em novembro de 2023 pelo prefeito Diego Sorgatto (UB), o servi\u00e7o registra crescimento de 355% no n\u00famero de passageiros ao longo de pouco mais de um ano de opera\u00e7\u00e3o, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-4539","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4539"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4539\/revisions"}],"predecessor-version":[{"id":4541,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4539\/revisions\/4541"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4540"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}