{"id":4664,"date":"2025-02-28T09:49:40","date_gmt":"2025-02-28T12:49:40","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4664"},"modified":"2025-02-28T09:49:40","modified_gmt":"2025-02-28T12:49:40","slug":"escola-do-futuro-de-valparaiso-recebe-biodigestor-autonomo-da-embaixada-de-israel","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/02\/28\/escola-do-futuro-de-valparaiso-recebe-biodigestor-autonomo-da-embaixada-de-israel\/","title":{"rendered":"Escola do Futuro de Valpara\u00edso recebe biodigestor aut\u00f4nomo da Embaixada de Israel"},"content":{"rendered":"<p><strong>Sustentabilidade e educa\u00e7\u00e3o ambiental<\/strong><\/p>\n<p>Nesta quinta-feira, 27 de fevereiro, a Escola do Futuro Paulo Renato de Souza, em Valpara\u00edso, inaugurou o Biodigestor Aut\u00f4nomo Homebiogas, doado pela Embaixada de Israel. Este equipamento transforma res\u00edduos org\u00e2nicos em biog\u00e1s e biofertilizante, refor\u00e7ando o compromisso da unidade escolar com pr\u00e1ticas inovadoras e sustent\u00e1veis.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Autoridades destacam relev\u00e2ncia<\/strong><\/p>\n<p>Durante a cerim\u00f4nia, autoridades ressaltaram a import\u00e2ncia do projeto. O prefeito de Valpara\u00edso, Marcus Vinicius, celebrou a iniciativa, destacando o pioneirismo do munic\u00edpio na ado\u00e7\u00e3o dessa tecnologia. \u201c\u00c9 uma alegria imensa! Valpara\u00edso agora faz parte da agenda ambiental e de sustentabilidade. Esse biodigestor gera economia de g\u00e1s e aproveita res\u00edduos org\u00e2nicos na aduba\u00e7\u00e3o de hortas e \u00e1reas verdes. Somos a primeira cidade a receber esse equipamento, gra\u00e7as \u00e0 parceria com o Governo do Estado de Goi\u00e1s\u201d, comemorou o prefeito.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Parceria com Israel<\/strong><\/p>\n<p>O embaixador de Israel, Daniel Dohar Zonshine, refor\u00e7ou a import\u00e2ncia do investimento em pesquisa e tecnologia. \u201cEste biodigestor, apesar de parecer simples, carrega muita experi\u00eancia e desenvolvimento. O papel da escola \u00e9 promover inova\u00e7\u00e3o e aprendizado para que os alunos entendam a import\u00e2ncia da preserva\u00e7\u00e3o ambiental\u201d, enfatizou o diplomata.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Projeto \u00d3asis e infraestrutura<\/strong><\/p>\n<p>O secret\u00e1rio de Estado de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o, Jos\u00e9 Frederico Lyra Netto, destacou que a iniciativa faz parte do Projeto \u00d3asis, do Governo de Goi\u00e1s, que visa tornar as escolas mais sustent\u00e1veis e tecnologicamente avan\u00e7adas. \u201cAs Escolas do Futuro t\u00eam infraestrutura de ponta e um compromisso com a forma\u00e7\u00e3o de jovens em tecnologia. A ades\u00e3o ao biodigestor \u00e9 mais um passo na dire\u00e7\u00e3o de um ensino inovador e comprometido com o meio ambiente\u201d, ressaltou o secret\u00e1rio.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Impacto positivo<\/strong><\/p>\n<p>A diretora da Escola do Futuro, Alcione Martins, celebrou a chegada do equipamento e destacou seu impacto positivo. \u201cEstamos muito felizes com essa doa\u00e7\u00e3o. A demanda para ingressar na escola \u00e9 enorme, e nosso projeto Jornada para o Futuro tem sido um sucesso. Agora, com o biodigestor, damos mais um passo para nos tornarmos um modelo de educa\u00e7\u00e3o ambiental.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Refer\u00eancia em educa\u00e7\u00e3o<\/strong><\/p>\n<p>O vice-governador de Goi\u00e1s, Daniel Vilela, ressaltou que, mesmo inaugurada h\u00e1 apenas um ano e meio, a Escola do Futuro de Valpara\u00edso j\u00e1 \u00e9 refer\u00eancia. \u201cOferecemos um ensino profissionalizante integrado com o ensino regular. Nossos alunos seguem a grade do ensino m\u00e9dio pela manh\u00e3 e desenvolvem habilidades tecnol\u00f3gicas \u00e0 tarde, essenciais para o sucesso profissional. A Escola do Futuro tem feito a diferen\u00e7a e tem sido um grande sucesso\u201d, comemorou o vice-governador.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Compromisso com a educa\u00e7\u00e3o sustent\u00e1vel<\/strong><\/p>\n<p>A professora Aleth\u00e9ia Cruz, representante da Funda\u00e7\u00e3o de Apoio \u00e0 Pesquisa (FUNAPE) da Universidade Federal de Goi\u00e1s (UFG), destacou a relev\u00e2ncia da iniciativa. \u201cO biodigestor \u00e9 uma solu\u00e7\u00e3o inovadora para o problema dos res\u00edduos s\u00f3lidos. A doa\u00e7\u00e3o da Embaixada de Israel refor\u00e7a o compromisso do Governo do Estado com o meio ambiente e a educa\u00e7\u00e3o sustent\u00e1vel. Este equipamento ser\u00e1 um ponto de refer\u00eancia para toda a comunidade de Valpara\u00edso.\u201d<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Escola do Futuro<\/strong><\/p>\n<p>A Escola do Futuro \u00e9 vinculada ao Governo do Estado de Goi\u00e1s, sob responsabilidade da Secretaria de Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (SECTI), com apoio da Universidade Federal de Goi\u00e1s (UFG) e do Goi\u00e1s Social. Em Valpara\u00edso, a Escola do Futuro Paulo Renato de Souza est\u00e1 localizada na Rua 60, quadra 05B, s\/n\u00ba, Jardim C\u00e9u Azul. Outras informa\u00e7\u00f5es pelo telefone (62) 99889-9035 ou pelo e-mail valparaisodegoias@efg.org.br.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sustentabilidade e educa\u00e7\u00e3o ambiental Nesta quinta-feira, 27 de fevereiro, a Escola do Futuro Paulo Renato de Souza, em Valpara\u00edso, inaugurou o Biodigestor Aut\u00f4nomo Homebiogas, doado pela Embaixada de Israel. Este equipamento transforma res\u00edduos org\u00e2nicos em biog\u00e1s e biofertilizante, refor\u00e7ando o compromisso da unidade escolar com pr\u00e1ticas inovadoras e sustent\u00e1veis. &nbsp; Autoridades destacam relev\u00e2ncia Durante a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4665,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4664","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4664"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4664\/revisions"}],"predecessor-version":[{"id":4666,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4664\/revisions\/4666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4665"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}