{"id":4688,"date":"2025-03-05T09:20:17","date_gmt":"2025-03-05T12:20:17","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4688"},"modified":"2025-03-05T09:20:17","modified_gmt":"2025-03-05T12:20:17","slug":"panela-esquecida-no-fogo-mobiliza-bombeiros-e-assusta-moradores-em-santo-andre","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/03\/05\/panela-esquecida-no-fogo-mobiliza-bombeiros-e-assusta-moradores-em-santo-andre\/","title":{"rendered":"Panela esquecida no fogo mobiliza bombeiros e assusta moradores em Santo Andr\u00e9"},"content":{"rendered":"<p><strong>Fuma\u00e7a causa preocupa\u00e7\u00e3o<\/strong><\/p>\n<p>Na noite de ter\u00e7a-feira (4\/03), uma intensa fuma\u00e7a saindo de um apartamento na rua Xingu, em Santo Andr\u00e9, deixou moradores e vizinhos preocupados. O incidente, causado por uma panela esquecida no fogo, gerou uma grande mobiliza\u00e7\u00e3o no bairro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Atua\u00e7\u00e3o do Corpo de Bombeiros<\/strong><\/p>\n<p>O Corpo de Bombeiros enviou quatro viaturas ao local, como medida preventiva, devido \u00e0 dificuldade de avaliar a gravidade da situa\u00e7\u00e3o apenas pelas informa\u00e7\u00f5es recebidas. Felizmente, a ocorr\u00eancia n\u00e3o registrou v\u00edtimas.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Trabalho acompanhado pela comunidade<\/strong><\/p>\n<p>Os moradores acompanharam das cal\u00e7adas o trabalho das equipes, que controlaram o incidente com efici\u00eancia. Segundo os bombeiros, em situa\u00e7\u00f5es desse tipo, a fuma\u00e7a pode alarmar a vizinhan\u00e7a, exigindo r\u00e1pida atua\u00e7\u00e3o para evitar riscos maiores.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Fuma\u00e7a causa preocupa\u00e7\u00e3o Na noite de ter\u00e7a-feira (4\/03), uma intensa fuma\u00e7a saindo de um apartamento na rua Xingu, em Santo Andr\u00e9, deixou moradores e vizinhos preocupados. O incidente, causado por uma panela esquecida no fogo, gerou uma grande mobiliza\u00e7\u00e3o no bairro. &nbsp; Atua\u00e7\u00e3o do Corpo de Bombeiros O Corpo de Bombeiros enviou quatro viaturas ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4689,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4688"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4688\/revisions"}],"predecessor-version":[{"id":4690,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4688\/revisions\/4690"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4689"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}