{"id":4994,"date":"2025-04-09T09:38:55","date_gmt":"2025-04-09T12:38:55","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=4994"},"modified":"2025-04-09T09:38:55","modified_gmt":"2025-04-09T12:38:55","slug":"olheiro-do-palmeiras-avalia-talentos-sub-9-a-sub-15-em-valparaiso-no-dia-23-de-abril","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/04\/09\/olheiro-do-palmeiras-avalia-talentos-sub-9-a-sub-15-em-valparaiso-no-dia-23-de-abril\/","title":{"rendered":"Olheiro do Palmeiras avalia talentos sub-9 a sub-15 em Valpara\u00edso no dia 23 de abril"},"content":{"rendered":"<p>Atletas de base de Valpara\u00edso de Goi\u00e1s e regi\u00e3o ter\u00e3o a chance de serem avaliados pelo \u201colheiro\u201d Dunda, representante do Palmeiras de S\u00e3o Paulo. O evento, marcado para o dia 23 de abril a partir das 13h, acontecer\u00e1 no Centro Poliesportivo do C\u00e9u Azul, na Pra\u00e7a Central do C\u00e9u Azul, com o apoio da Secretaria Municipal de Cultura e Esporte de Valpara\u00edso e de Mar\u00edlia Rocha.<\/p>\n<p>A prioridade na sele\u00e7\u00e3o ser\u00e1 para os atletas residentes em Valpara\u00edso; participantes de outras localidades poder\u00e3o se inscrever caso haja vagas dispon\u00edveis. \u201cEssa \u00e9 uma oportunidade imperd\u00edvel para crian\u00e7as e jovens que sonham em seguir no futebol. Acreditamos que daqui podem surgir novos craques\u201d, destacou Mar\u00edlia Rocha.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Categorias e Requisitos:<\/strong><\/p>\n<ul>\n<li><strong>Sub-9:<\/strong> Nascidos em 2016\/2017<\/li>\n<li><strong>Sub-11:<\/strong> Nascidos em 2014\/2015<\/li>\n<li><strong>Sub-13:<\/strong> Nascidos em 2012\/2013<\/li>\n<li><strong>Sub-15:<\/strong> Nascidos em 2010\/2011<\/li>\n<\/ul>\n<p>A avalia\u00e7\u00e3o \u00e9 totalmente gratuita. Os interessados devem preencher uma ficha de inscri\u00e7\u00e3o, que poder\u00e1 ser retirada em dois locais: \u2022 Secretaria de Cultura e Esporte (Quadra 24, Lote 48 \u2013 Etapa A \/ Valpara\u00edso I) \u2022 Casa da Cultura Mestre Sab\u00e1 (Rua 25, Quadra 87, Lote 27 \u2013 2\u00aa Etapa, bairro C\u00e9u Azul \u2013 Refer\u00eancia: Avenida do Col\u00e9gio Militar Fernando Pessoa)<\/p>\n<p>No ato da inscri\u00e7\u00e3o, \u00e9 necess\u00e1rio apresentar 1kg de alimento n\u00e3o perec\u00edvel (observa\u00e7\u00e3o: n\u00e3o ser\u00e3o aceitos itens como floc\u00e3o, sal ou milharina). Os atletas aprovados seguir\u00e3o para uma nova bateria de testes, que ser\u00e1 realizada no CT do Palmeiras, em S\u00e3o Paulo, em data a ser definida.<\/p>\n<p>Com essa iniciativa, o Palmeiras refor\u00e7a seu compromisso com o esporte de base, buscando identificar e incentivar os futuros talentos do futebol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atletas de base de Valpara\u00edso de Goi\u00e1s e regi\u00e3o ter\u00e3o a chance de serem avaliados pelo \u201colheiro\u201d Dunda, representante do Palmeiras de S\u00e3o Paulo. O evento, marcado para o dia 23 de abril a partir das 13h, acontecer\u00e1 no Centro Poliesportivo do C\u00e9u Azul, na Pra\u00e7a Central do C\u00e9u Azul, com o apoio da Secretaria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4995,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-4994","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=4994"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994\/revisions"}],"predecessor-version":[{"id":4996,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/4994\/revisions\/4996"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4995"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=4994"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=4994"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=4994"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}