{"id":5026,"date":"2025-04-11T14:55:38","date_gmt":"2025-04-11T17:55:38","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5026"},"modified":"2025-04-11T14:55:38","modified_gmt":"2025-04-11T17:55:38","slug":"dra-zeli-visita-tecnoshow-em-rio-verde-e-destaca-forca-do-agronegocio-goiano","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/04\/11\/dra-zeli-visita-tecnoshow-em-rio-verde-e-destaca-forca-do-agronegocio-goiano\/","title":{"rendered":"Dra. Zeli visita Tecnoshow em Rio Verde e destaca for\u00e7a do agroneg\u00f3cio goiano"},"content":{"rendered":"<p>A deputada estadual Dra. Zeli (UB) participou nesta quinta-feira (10\/4) da <strong>22\u00aa edi\u00e7\u00e3o da Tecnoshow Comigo<\/strong>, em Rio Verde, considerada a maior feira de agroneg\u00f3cio do Centro-Oeste e uma das principais do Brasil. Em sua primeira visita \u00e0 regi\u00e3o Sudoeste de Goi\u00e1s, a parlamentar destacou a grandiosidade do evento e sua import\u00e2ncia para o desenvolvimento do estado.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante a feira, Dra. Zeli encontrou o presidente da Assembleia Legislativa, deputado Bruno Peixoto, e outras autoridades municipais e estaduais. Ambos concederam entrevista \u00e0 TV Band e R\u00e1dio Sucesso, onde a deputada ressaltou a oportunidade de aprender, trocar experi\u00eancias e ampliar sua atua\u00e7\u00e3o como representante do povo goiano.<\/p>\n<blockquote><p>\u201cConhecer o Sudoeste goiano e vivenciar de perto a pot\u00eancia que \u00e9 a Tecnoshow me fortalece como parlamentar. Goi\u00e1s \u00e9 uma refer\u00eancia no agro, e isso nos enche de orgulho,\u201d afirmou Dra. Zeli.<\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<p>A Tecnoshow, que se estende por cinco dias, transforma Rio Verde na capital simb\u00f3lica do estado, movimentando bilh\u00f5es em neg\u00f3cios e reunindo tecnologia, inova\u00e7\u00e3o e oportunidades para o setor produtivo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A deputada estadual Dra. Zeli (UB) participou nesta quinta-feira (10\/4) da 22\u00aa edi\u00e7\u00e3o da Tecnoshow Comigo, em Rio Verde, considerada a maior feira de agroneg\u00f3cio do Centro-Oeste e uma das principais do Brasil. Em sua primeira visita \u00e0 regi\u00e3o Sudoeste de Goi\u00e1s, a parlamentar destacou a grandiosidade do evento e sua import\u00e2ncia para o desenvolvimento [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-5026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5026"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5026\/revisions"}],"predecessor-version":[{"id":5028,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5026\/revisions\/5028"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5027"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}