{"id":5280,"date":"2025-04-25T11:24:54","date_gmt":"2025-04-25T14:24:54","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5280"},"modified":"2025-04-25T11:24:54","modified_gmt":"2025-04-25T14:24:54","slug":"distribuidora-de-bebidas-em-luziania-fachada-para-trafico-e-desmantelada","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/04\/25\/distribuidora-de-bebidas-em-luziania-fachada-para-trafico-e-desmantelada\/","title":{"rendered":"Distribuidora de bebidas em Luzi\u00e2nia, fachada para tr\u00e1fico, \u00e9 desmantelada"},"content":{"rendered":"<p>Uma opera\u00e7\u00e3o policial desmantelou uma distribuidora de bebidas localizada no Parque Estrela Dalva 9, em Luzi\u00e2nia, no Entorno do Distrito Federal, que funcionava como fachada para o tr\u00e1fico de drogas. A a\u00e7\u00e3o foi deflagrada ap\u00f3s den\u00fancias an\u00f4nimas que chamaram aten\u00e7\u00e3o para atividades suspeitas no local.<\/p>\n<p>Durante a opera\u00e7\u00e3o, o propriet\u00e1rio do estabelecimento, de 48 anos, foi preso enquanto embalava coca\u00edna, monitorando a atividade por meio de c\u00e2meras. Um c\u00famplice, de 25 anos, controlava o acesso ao im\u00f3vel, onde a aus\u00eancia de produtos no freezer levantou suspeitas quanto \u00e0 real finalidade do neg\u00f3cio.<\/p>\n<p>&nbsp;<\/p>\n<p>Quatro pessoas foram encaminhadas \u00e0 delegacia; duas delas foram liberadas por serem flagradas apenas com porte para consumo. O delegado Rafael Abr\u00e3o destacou que as den\u00fancias an\u00f4nimas foram fundamentais para o sucesso da opera\u00e7\u00e3o, que visa combater o uso de estabelecimentos comerciais como fachadas para atividades il\u00edcitas.<\/p>\n<p>A a\u00e7\u00e3o evidencia o comprometimento das autoridades no combate ao tr\u00e1fico de drogas, mesmo quando o crime \u00e9 disfar\u00e7ado em atividades de rotina, refor\u00e7ando a import\u00e2ncia da colabora\u00e7\u00e3o da popula\u00e7\u00e3o para o efetivo enfrentamento da criminalidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma opera\u00e7\u00e3o policial desmantelou uma distribuidora de bebidas localizada no Parque Estrela Dalva 9, em Luzi\u00e2nia, no Entorno do Distrito Federal, que funcionava como fachada para o tr\u00e1fico de drogas. A a\u00e7\u00e3o foi deflagrada ap\u00f3s den\u00fancias an\u00f4nimas que chamaram aten\u00e7\u00e3o para atividades suspeitas no local. Durante a opera\u00e7\u00e3o, o propriet\u00e1rio do estabelecimento, de 48 anos, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-5280","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5280"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5280\/revisions"}],"predecessor-version":[{"id":5282,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5280\/revisions\/5282"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5281"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}