{"id":5421,"date":"2025-05-09T09:34:17","date_gmt":"2025-05-09T12:34:17","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5421"},"modified":"2025-05-09T09:34:17","modified_gmt":"2025-05-09T12:34:17","slug":"apos-chegada-dos-novos-onibus-valparaiso-aguarda-veiculos-realmente-novos","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/05\/09\/apos-chegada-dos-novos-onibus-valparaiso-aguarda-veiculos-realmente-novos\/","title":{"rendered":"Ap\u00f3s chegada dos \u201cnovos\u201d \u00f4nibus, Valpara\u00edso aguarda ve\u00edculos realmente novos"},"content":{"rendered":"<p>Na manh\u00e3 desta quinta-feira, 8 de maio, o prefeito Marcus Vin\u00edcius lan\u00e7ou o sistema \u201cVai de Val\u201d, iniciativa que promete modernizar o transporte p\u00fablico em Valpara\u00edso de Goi\u00e1s. No entanto, os ve\u00edculos apresentados \u2013 que contam com recursos como c\u00e2meras modernas, detec\u00e7\u00e3o facial, acessibilidade e tarifa de R$ 2,90 \u2013 s\u00e3o, na verdade, \u00f4nibus reformados pela Via\u00e7\u00e3o Catedral, veterana na Regi\u00e3o Metropolitana do DF.<\/p>\n<p>Embora o projeto represente um avan\u00e7o para a mobilidade urbana, a popula\u00e7\u00e3o esperava a chegada de frotas novas, conforme anunciado inicialmente. Os \u00f4nibus utilizados foram retirados de circula\u00e7\u00e3o em uma cidade vizinha e passaram por revis\u00f5es, pintura e instala\u00e7\u00e3o de equipamentos de seguran\u00e7a, antes de serem enviados para Valpara\u00edso.<\/p>\n<p>&nbsp;<\/p>\n<p>Durante o evento, o prefeito destacou que o sistema \u201cVai de Val\u201d \u00e9 apenas o primeiro passo. Ele pretende ampliar a frota de 10 para 30 ve\u00edculos em breve e manifestou a inten\u00e7\u00e3o de, futuramente, negociar a aquisi\u00e7\u00e3o de \u00f4nibus novos, para que os compromissos assumidos no in\u00edcio do ano sejam cumpridos de fato.<\/p>\n<p>Al\u00e9m disso, o prefeito garantiu que apresentar\u00e1 um Projeto de Lei ainda neste m\u00eas de maio para viabilizar a gratuidade do servi\u00e7o aos domingos, ampliando os benef\u00edcios para a popula\u00e7\u00e3o. Enquanto isso, a comunidade monitora de perto os pr\u00f3ximos passos para transformar o transporte p\u00fablico local com ve\u00edculos modernos, verdadeiramente novos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na manh\u00e3 desta quinta-feira, 8 de maio, o prefeito Marcus Vin\u00edcius lan\u00e7ou o sistema \u201cVai de Val\u201d, iniciativa que promete modernizar o transporte p\u00fablico em Valpara\u00edso de Goi\u00e1s. No entanto, os ve\u00edculos apresentados \u2013 que contam com recursos como c\u00e2meras modernas, detec\u00e7\u00e3o facial, acessibilidade e tarifa de R$ 2,90 \u2013 s\u00e3o, na verdade, \u00f4nibus reformados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5422,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-5421","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5421"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5421\/revisions"}],"predecessor-version":[{"id":5423,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5421\/revisions\/5423"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5422"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5421"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5421"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}