{"id":5433,"date":"2025-05-10T09:01:20","date_gmt":"2025-05-10T12:01:20","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5433"},"modified":"2025-05-10T09:01:20","modified_gmt":"2025-05-10T12:01:20","slug":"luziania-se-destaca-em-reuniao-da-camara-sobre-transporte-gratuito","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/05\/10\/luziania-se-destaca-em-reuniao-da-camara-sobre-transporte-gratuito\/","title":{"rendered":"Luzi\u00e2nia se destaca em reuni\u00e3o da C\u00e2mara sobre transporte gratuito"},"content":{"rendered":"<p>Durante a reuni\u00e3o da Comiss\u00e3o de Desenvolvimento Urbano da C\u00e2mara dos Deputados, realizada nesta ter\u00e7a-feira (6), Luzi\u00e2nia foi apontada como refer\u00eancia nacional na implementa\u00e7\u00e3o da tarifa zero no transporte p\u00fablico. O encontro, que reuniu parlamentares, especialistas e representantes de diversas regi\u00f5es, destacou o modelo adotado pela gest\u00e3o do prefeito Diego Sorgatto, que tem beneficiado milhares de moradores, especialmente das \u00e1reas mais afastadas, por meio do transporte gratuito.<\/p>\n<p>O deputado distrital Max Maciel (Psol), presidente da Comiss\u00e3o de Transporte e Mobilidade Urbana da C\u00e2mara Legislativa do Distrito Federal, enalteceu o exemplo de Luzi\u00e2nia, ressaltando a viabilidade e os impactos positivos do programa na qualidade de vida da popula\u00e7\u00e3o. Segundo Maciel, a iniciativa demonstra que \u00e9 poss\u00edvel garantir um servi\u00e7o gratuito, com impacto or\u00e7ament\u00e1rio reduzido, promovendo a inclus\u00e3o social e facilitando o acesso a servi\u00e7os essenciais, como sa\u00fade, educa\u00e7\u00e3o e trabalho.<\/p>\n<p>&nbsp;<\/p>\n<p>Al\u00e9m disso, durante a reuni\u00e3o foram apresentados dados que mostram que 132 cidades brasileiras j\u00e1 adotaram o transporte p\u00fablico gratuito, beneficiando cerca de 7,4 milh\u00f5es de pessoas com um impacto m\u00e9dio de apenas 2% no or\u00e7amento municipal. O caso de Luzi\u00e2nia foi citado como um exemplo de planejamento e compromisso com a mobilidade urbana, provando que pol\u00edticas p\u00fablicas eficientes podem transformar positivamente a vida dos cidad\u00e3os.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante a reuni\u00e3o da Comiss\u00e3o de Desenvolvimento Urbano da C\u00e2mara dos Deputados, realizada nesta ter\u00e7a-feira (6), Luzi\u00e2nia foi apontada como refer\u00eancia nacional na implementa\u00e7\u00e3o da tarifa zero no transporte p\u00fablico. O encontro, que reuniu parlamentares, especialistas e representantes de diversas regi\u00f5es, destacou o modelo adotado pela gest\u00e3o do prefeito Diego Sorgatto, que tem beneficiado milhares [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5434,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-5433","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5433","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5433"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5433\/revisions"}],"predecessor-version":[{"id":5435,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5433\/revisions\/5435"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5434"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5433"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5433"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5433"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}