{"id":5439,"date":"2025-05-10T09:05:39","date_gmt":"2025-05-10T12:05:39","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5439"},"modified":"2025-05-10T09:05:39","modified_gmt":"2025-05-10T12:05:39","slug":"ifg-abre-inscricoes-para-curso-de-educacao-em-direitos-humanos-em-quatro-campus","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/05\/10\/ifg-abre-inscricoes-para-curso-de-educacao-em-direitos-humanos-em-quatro-campus\/","title":{"rendered":"IFG abre inscri\u00e7\u00f5es para curso de Educa\u00e7\u00e3o em Direitos Humanos em quatro c\u00e2mpus"},"content":{"rendered":"<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para o curso de forma\u00e7\u00e3o continuada em Direitos Humanos, ofertado pelo Instituto Federal de Goi\u00e1s (IFG) por meio da Pr\u00f3-Reitoria de Extens\u00e3o (Proex). O edital, n\u00ba 13\/2025\/PROEX\/IFG, estabelece que os interessados \u2013 professores, coordenadores pedag\u00f3gicos ou gestores da rede p\u00fablica de Educa\u00e7\u00e3o B\u00e1sica \u2013 devem se inscrever at\u00e9 6 de junho, exclusivamente pelo link: <button type=\"button\" data-url=\"https:\/\/forms.gle\/HJPvBvruV5g1noap9\">https:\/\/forms.gle\/HJPvBvruV5g1noap9<\/button>.<\/p>\n<p>Para participar, o candidato dever\u00e1 preencher o formul\u00e1rio e enviar, em um \u00fanico arquivo PDF, os seguintes documentos na ordem indicada: documento com foto e CPF; diploma de gradua\u00e7\u00e3o em curso de licenciatura; comprovante de tempo de servi\u00e7o na Educa\u00e7\u00e3o B\u00e1sica; e carta de motiva\u00e7\u00e3o que detalhe sua trajet\u00f3ria profissional e interesses no campo dos Direitos Humanos em Educa\u00e7\u00e3o. \u00c9 necess\u00e1rio ter gradua\u00e7\u00e3o em pedagogia ou outra licenciatura, disponibilidade m\u00ednima de quatro horas semanais para os encontros presenciais e acesso a um computador com internet.<\/p>\n<p>&nbsp;<\/p>\n<p>O curso, que contar\u00e1 com atividades presenciais e a dist\u00e2ncia (s\u00edncronas e ass\u00edncronas), ter\u00e1 aulas te\u00f3ricas e pr\u00e1ticas ministradas entre maio e novembro deste ano, com cada turma limitada a 50 alunos por polo. As vagas est\u00e3o dispon\u00edveis para os c\u00e2mpus de \u00c1guas Lindas, Formosa, Luzi\u00e2nia e Valpara\u00edso. O resultado ser\u00e1 divulgado em 18 de junho, com aula inaugural marcada para 28 do mesmo m\u00eas.<\/p>\n<p>Esta oferta, financiada pela Secretaria de Educa\u00e7\u00e3o Continuada, Alfabetiza\u00e7\u00e3o de Jovens e Adultos, Diversidade e Inclus\u00e3o do MEC (SECADI\/MEC), representa uma oportunidade de qualifica\u00e7\u00e3o para os profissionais da Educa\u00e7\u00e3o B\u00e1sica, capacitando-os para atuar no campo dos Direitos Humanos e ampliando sua forma\u00e7\u00e3o continuada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Est\u00e3o abertas as inscri\u00e7\u00f5es para o curso de forma\u00e7\u00e3o continuada em Direitos Humanos, ofertado pelo Instituto Federal de Goi\u00e1s (IFG) por meio da Pr\u00f3-Reitoria de Extens\u00e3o (Proex). O edital, n\u00ba 13\/2025\/PROEX\/IFG, estabelece que os interessados \u2013 professores, coordenadores pedag\u00f3gicos ou gestores da rede p\u00fablica de Educa\u00e7\u00e3o B\u00e1sica \u2013 devem se inscrever at\u00e9 6 de junho, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4870,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-5439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5439"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5439\/revisions"}],"predecessor-version":[{"id":5440,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5439\/revisions\/5440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/4870"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}