{"id":5722,"date":"2025-06-09T17:36:51","date_gmt":"2025-06-09T20:36:51","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5722"},"modified":"2025-06-09T17:36:51","modified_gmt":"2025-06-09T20:36:51","slug":"dnit-inicia-estudos-topograficos-para-obras-emergenciais-na-br-040-em-valparaiso","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/06\/09\/dnit-inicia-estudos-topograficos-para-obras-emergenciais-na-br-040-em-valparaiso\/","title":{"rendered":"DNIT inicia estudos topogr\u00e1ficos para obras emergenciais na BR-040 em Valpara\u00edso"},"content":{"rendered":"<p>O Departamento Nacional de Infraestrutura de Transportes (DNIT) iniciou, no \u00faltimo s\u00e1bado (7), estudos topogr\u00e1ficos e mapeamento com drones na regi\u00e3o da Vo\u00e7oroca, em Valpara\u00edso (GO). A a\u00e7\u00e3o faz parte da prepara\u00e7\u00e3o para obras emergenciais na BR-040, visando conter eros\u00f5es e acabar com alagamentos recorrentes na rodovia.<\/p>\n<p>Interven\u00e7\u00f5es e articula\u00e7\u00e3o pol\u00edtica<br \/>\nOs levantamentos t\u00e9cnicos s\u00e3o conduzidos pela empresa Dynatest, contratada pelo DNIT, e subsidiar\u00e3o as futuras interven\u00e7\u00f5es. A iniciativa \u00e9 fruto de articula\u00e7\u00e3o entre o senador Vanderlan Cardoso, o deputado federal C\u00e9lio Silveira e o ministro dos Transportes, Renan Filho, com apoio da gest\u00e3o municipal.<\/p>\n<p>\u201cO resultado desse estudo vai complementar os levantamentos j\u00e1 realizados pelo DNIT, permitindo uma interven\u00e7\u00e3o r\u00e1pida e eficaz\u201d, afirmou o prefeito Marcus Vinicius.<\/p>\n<p>Investimentos para drenagem da BR-040<br \/>\nAl\u00e9m das obras emergenciais, a Prefeitura de Valpara\u00edso e o deputado C\u00e9lio Silveira t\u00eam reuni\u00e3o agendada com o Ministro das Cidades na pr\u00f3xima semana. O encontro discutir\u00e1 a libera\u00e7\u00e3o de R$ 50 milh\u00f5es para obras de drenagem na BR-040, uma medida essencial para eliminar os constantes alagamentos que afetam a popula\u00e7\u00e3o.<\/p>\n<p>Com os estudos em andamento e as obras previstas, a expectativa \u00e9 de que os problemas na Vo\u00e7oroca sejam solucionados em breve, garantindo mais seguran\u00e7a e infraestrutura para os moradores de Valpara\u00edso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Departamento Nacional de Infraestrutura de Transportes (DNIT) iniciou, no \u00faltimo s\u00e1bado (7), estudos topogr\u00e1ficos e mapeamento com drones na regi\u00e3o da Vo\u00e7oroca, em Valpara\u00edso (GO). A a\u00e7\u00e3o faz parte da prepara\u00e7\u00e3o para obras emergenciais na BR-040, visando conter eros\u00f5es e acabar com alagamentos recorrentes na rodovia. Interven\u00e7\u00f5es e articula\u00e7\u00e3o pol\u00edtica Os levantamentos t\u00e9cnicos s\u00e3o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5723,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-5722","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5722","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5722"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5722\/revisions"}],"predecessor-version":[{"id":5724,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5722\/revisions\/5724"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5723"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5722"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5722"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5722"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}