{"id":5736,"date":"2025-06-10T18:48:37","date_gmt":"2025-06-10T21:48:37","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5736"},"modified":"2025-06-10T18:48:37","modified_gmt":"2025-06-10T21:48:37","slug":"alagoas-tem-50-apostas-premiadas-na-quadra-da-mega-sena-acumulada","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/06\/10\/alagoas-tem-50-apostas-premiadas-na-quadra-da-mega-sena-acumulada\/","title":{"rendered":"Alagoas tem 50 apostas premiadas na quadra da Mega-Sena acumulada"},"content":{"rendered":"<p>No \u00faltimo s\u00e1bado, durante o concurso 2873 da Mega-Sena, o estado de Alagoas registrou 50 apostas premiadas na faixa da quadra. Apesar dos acertadores terem garantido seus pr\u00eamios de R$ 681,13 cada, o pr\u00eamio principal n\u00e3o teve ganhador, acumulando para o pr\u00f3ximo sorteio, previsto para ter\u00e7a-feira, com uma estimativa de R$ 61 milh\u00f5es. As dezenas sorteadas foram 04, 05, 17, 27, 52 e 56.<\/p>\n<p>A Caixa Econ\u00f4mica Federal informou que, al\u00e9m das 50 apostas na quadra, 95 apostas acertaram a quina, recebendo R$ 44.356,88 cada. No estado, os bilhetes premiados foram distribu\u00eddos por diversas cidades, como Macei\u00f3, que se destacou com 17 apostas vencedoras, e Arapiraca, com nove bilhetes premiados. Outras cidades contempladas incluem Delmiro Gouveia, Flexeiras, Girau do Ponciano, Ibateguara, Maragogi, Marechal Deodoro, Palmeira dos \u00cdndios, P\u00e3o de A\u00e7\u00facar, Penedo, Pilar, Piranhas, Porto Calvo, Porto Real do Col\u00e9gio, Rio Largo, Santana do Ipanema, S\u00e3o Miguel dos Campos, Uni\u00e3o dos Palmares e Vi\u00e7osa.<\/p>\n<p>&nbsp;<\/p>\n<p>Para participar do pr\u00f3ximo sorteio, os interessados podem registrar suas apostas at\u00e9 as 19h do dia do sorteio em qualquer casa lot\u00e9rica credenciada ou atrav\u00e9s do site oficial das Loterias Caixa. A aposta simples, composta por seis dezenas, custa R$ 5, mas h\u00e1 tamb\u00e9m a op\u00e7\u00e3o de apostas m\u00faltiplas e bol\u00f5es, que possibilitam marcar mais n\u00fameros e dividir os custos.<\/p>\n<p>Com o pr\u00eamio acumulado em R$ 61 milh\u00f5es, a expectativa \u00e9 de aumento na ades\u00e3o dos apostadores para o concurso que ser\u00e1 realizado na ter\u00e7a-feira, 10 de junho de 2025. O sorteio pode ser acompanhado ao vivo pelas redes sociais das Loterias Caixa ou no canal oficial do YouTube, garantindo que os interessados verifiquem rapidamente os resultados e, quem sabe, se tornem os pr\u00f3ximos premiados.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>No \u00faltimo s\u00e1bado, durante o concurso 2873 da Mega-Sena, o estado de Alagoas registrou 50 apostas premiadas na faixa da quadra. Apesar dos acertadores terem garantido seus pr\u00eamios de R$ 681,13 cada, o pr\u00eamio principal n\u00e3o teve ganhador, acumulando para o pr\u00f3ximo sorteio, previsto para ter\u00e7a-feira, com uma estimativa de R$ 61 milh\u00f5es. As dezenas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5737,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-5736","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5736","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5736"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5736\/revisions"}],"predecessor-version":[{"id":5738,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5736\/revisions\/5738"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5737"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5736"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5736"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5736"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}