{"id":5948,"date":"2025-06-26T14:54:39","date_gmt":"2025-06-26T17:54:39","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=5948"},"modified":"2025-06-26T14:54:39","modified_gmt":"2025-06-26T17:54:39","slug":"valparaiso-realiza-arraia-de-doacao-de-livros-nesta-sexta-27","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/06\/26\/valparaiso-realiza-arraia-de-doacao-de-livros-nesta-sexta-27\/","title":{"rendered":"Valpara\u00edso realiza Arrai\u00e1 de Doa\u00e7\u00e3o de Livros nesta sexta (27)"},"content":{"rendered":"<p>A Secretaria Municipal de Cultura e Esporte de Valpara\u00edso promove, nesta sexta-feira (27\/06), das 8h30 \u00e0s 16h, o \u201cArrai\u00e1 de Doa\u00e7\u00e3o de Livros\u201d, na Biblioteca Cora Coralina, para estimular o h\u00e1bito da leitura e democratizar o acesso ao conhecimento.<\/p>\n<p>No evento, que ocorre no Edif\u00edcio Torre Center (Quadra 03, Lote 42, Avenida 15 de Junho \u2013 Valpara\u00edso II), ser\u00e3o distribu\u00eddos gratuitamente exemplares de diferentes \u00e1reas, como literatura, direito, ci\u00eancias sociais e infantojuvenil.<\/p>\n<p>A programa\u00e7\u00e3o n\u00e3o ter\u00e1 apenas a entrega de obras: os participantes poder\u00e3o conhecer o acervo da biblioteca, receber orienta\u00e7\u00f5es de volunt\u00e1rios sobre g\u00eaneros liter\u00e1rios e formar turmas de leitura informal para aproveitar melhor o material dispon\u00edvel.<\/p>\n<p>A a\u00e7\u00e3o refor\u00e7a o compromisso da Prefeitura em ampliar a oferta cultural e educacional \u00e0 comunidade. Segundo a secret\u00e1ria municipal de Cultura e Esporte, \u201cesta \u00e9 uma oportunidade de renovar as estantes, compartilhar hist\u00f3rias e aproximar Valpara\u00edso do universo da leitura\u201d.<\/p>\n<p>Servi\u00e7o Evento: Arrai\u00e1 de Doa\u00e7\u00e3o de Livros Data: Sexta-feira, 27 de junho Hor\u00e1rio: 8h30 \u00e0s 16h Local: Biblioteca Cora Coralina \u2013 Ed. Torre Center, Qd. 03, Lt. 42, Av. 15 de Junho, Valpara\u00edso II<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria Municipal de Cultura e Esporte de Valpara\u00edso promove, nesta sexta-feira (27\/06), das 8h30 \u00e0s 16h, o \u201cArrai\u00e1 de Doa\u00e7\u00e3o de Livros\u201d, na Biblioteca Cora Coralina, para estimular o h\u00e1bito da leitura e democratizar o acesso ao conhecimento. No evento, que ocorre no Edif\u00edcio Torre Center (Quadra 03, Lote 42, Avenida 15 de Junho [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[32],"tags":[],"class_list":["post-5948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-valparaiso","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=5948"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5948\/revisions"}],"predecessor-version":[{"id":5950,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/5948\/revisions\/5950"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/5949"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=5948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=5948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=5948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}