{"id":6594,"date":"2025-08-27T18:07:30","date_gmt":"2025-08-27T21:07:30","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=6594"},"modified":"2025-08-27T18:07:30","modified_gmt":"2025-08-27T21:07:30","slug":"damares-alves-anuncia-diagnostico-precoce-de-cancer-de-mama","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/08\/27\/damares-alves-anuncia-diagnostico-precoce-de-cancer-de-mama\/","title":{"rendered":"Damares Alves anuncia diagn\u00f3stico precoce de c\u00e2ncer de mama"},"content":{"rendered":"<p>A senadora Damares Alves (Republicanos-DF) revelou nesta quarta-feira, durante a instala\u00e7\u00e3o da subcomiss\u00e3o do C\u00e2ncer na Comiss\u00e3o de Sa\u00fade do Senado, que foi diagnosticada com c\u00e2ncer de mama h\u00e1 cerca de um m\u00eas. Em alus\u00e3o \u00e0 pr\u00f3pria luta, ela declarou: \u201cEu serei a membro mais leg\u00edtima da Comiss\u00e3o, porque eu estou enfrentando isso\u201d.<\/p>\n<p>Damares explicou que, ap\u00f3s o diagn\u00f3stico precoce, conseguiu realizar a cirurgia para retirada do tumor em 18 dias e retornou ao trabalho no Senado apenas cinco dias depois, apesar das dores. \u201cO diagn\u00f3stico precoce foi fundamental para eu estar como estou\u201d, afirmou.<\/p>\n<p>Em raz\u00e3o do tratamento e do desgaste f\u00edsico, a senadora precisou adiar a leitura de informes que seriam discutidos na reuni\u00e3o. \u201cEstou no meu limite f\u00edsico neste momento, mas na pr\u00f3xima semana espero retomar as sess\u00f5es sem restri\u00e7\u00f5es\u201d, disse.<\/p>\n<p>Ao justificar a decis\u00e3o de tornar p\u00fablica a doen\u00e7a, Damares ressaltou a coragem de compartilhar o relato e aproveitou para incentivar mulheres a praticarem o autoexame e a realizarem mamografias regularmente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A senadora Damares Alves (Republicanos-DF) revelou nesta quarta-feira, durante a instala\u00e7\u00e3o da subcomiss\u00e3o do C\u00e2ncer na Comiss\u00e3o de Sa\u00fade do Senado, que foi diagnosticada com c\u00e2ncer de mama h\u00e1 cerca de um m\u00eas. Em alus\u00e3o \u00e0 pr\u00f3pria luta, ela declarou: \u201cEu serei a membro mais leg\u00edtima da Comiss\u00e3o, porque eu estou enfrentando isso\u201d. Damares explicou [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6594"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6594\/revisions"}],"predecessor-version":[{"id":6596,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6594\/revisions\/6596"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/6595"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}