{"id":6858,"date":"2025-10-02T14:10:07","date_gmt":"2025-10-02T17:10:07","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=6858"},"modified":"2025-10-02T14:10:07","modified_gmt":"2025-10-02T17:10:07","slug":"elon-musk-ultrapassa-us-500-bilhoes-e-amplia-lideranca-entre-bilionarios","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/10\/02\/elon-musk-ultrapassa-us-500-bilhoes-e-amplia-lideranca-entre-bilionarios\/","title":{"rendered":"Elon Musk ultrapassa US$ 500 bilh\u00f5es e amplia lideran\u00e7a entre bilion\u00e1rios"},"content":{"rendered":"<p>Elon Musk se tornou nesta quarta-feira (1\u00ba) o primeiro bilion\u00e1rio do mundo a registrar um patrim\u00f4nio acima de US$ 500 bilh\u00f5es, segundo o ranking da revista Forbes. O marco supera o recorde anterior de US$ 400 bilh\u00f5es, atingido pelo executivo em 2021, e o coloca US$ 150 bilh\u00f5es \u00e0 frente de Larry Ellison, segundo colocado.<\/p>\n<p>A maior fatia da fortuna de Musk vem de sua participa\u00e7\u00e3o na Tesla, avaliada em US$ 191 bilh\u00f5es. Nesta quarta, as a\u00e7\u00f5es da fabricante de carros el\u00e9tricos subiram quase 4%, impulsionando ainda mais seu patrim\u00f4nio.<\/p>\n<p>Al\u00e9m da Tesla, Musk det\u00e9m 42% da SpaceX, estimados em US$ 168 bilh\u00f5es, e controla empresas de intelig\u00eancia artificial e m\u00eddia social reunidas na xAI, que correspondem a cerca de US$ 60 bilh\u00f5es de sua riqueza.<\/p>\n<p>Nascido na \u00c1frica do Sul, Musk \u00e9 tamb\u00e9m fundador da X (antigo Twitter) e de outras startups de energia e transporte espacial. Sua escalada ao topo da lista refor\u00e7a o dom\u00ednio de executivos do setor de tecnologia no ranking global de bilion\u00e1rios, compilado diariamente pela Forbes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Elon Musk se tornou nesta quarta-feira (1\u00ba) o primeiro bilion\u00e1rio do mundo a registrar um patrim\u00f4nio acima de US$ 500 bilh\u00f5es, segundo o ranking da revista Forbes. O marco supera o recorde anterior de US$ 400 bilh\u00f5es, atingido pelo executivo em 2021, e o coloca US$ 150 bilh\u00f5es \u00e0 frente de Larry Ellison, segundo colocado. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6859,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6858"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6858\/revisions"}],"predecessor-version":[{"id":6860,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6858\/revisions\/6860"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/6859"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}