{"id":6889,"date":"2025-10-06T12:50:52","date_gmt":"2025-10-06T15:50:52","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=6889"},"modified":"2025-10-06T12:50:52","modified_gmt":"2025-10-06T15:50:52","slug":"3-140-candidatos-fazem-prova-para-vagas-no-colegio-da-policia-militar-neste-domingo","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/10\/06\/3-140-candidatos-fazem-prova-para-vagas-no-colegio-da-policia-militar-neste-domingo\/","title":{"rendered":"3.140 candidatos fazem prova para vagas no Col\u00e9gio da Pol\u00edcia Militar neste domingo"},"content":{"rendered":"<p>A Secretaria de Estado de Pol\u00edcia Militar aplica hoje (5) na Uerj a prova de admiss\u00e3o para 133 vagas no Col\u00e9gio da Pol\u00edcia Militar, com 3.140 inscritos, em sua maioria dependentes de militares, disputando vagas no Ensino Fundamental Anos Finais e no Ensino M\u00e9dio.<\/p>\n<p>Do total de oportunidades, 75 vagas s\u00e3o para o 6\u00ba ano, distribu\u00eddas entre as unidades de Campo Grande, Duque de Caxias e Niter\u00f3i; 30 vagas para o 9\u00ba ano na unidade de Duque de Caxias; 8 vagas para o 1\u00ba ano do Ensino M\u00e9dio em Campo Grande; e 20 vagas para o 3\u00ba ano do Ensino M\u00e9dio em Niter\u00f3i.<\/p>\n<p>As inscri\u00e7\u00f5es, encerradas em 16 de setembro, confirmaram o interesse de milhares de fam\u00edlias em garantir a educa\u00e7\u00e3o militarizada oferecida pelo col\u00e9gio. O resultado das provas ser\u00e1 divulgado nos pr\u00f3ximos dias no site do Col\u00e9gio da Pol\u00edcia Militar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Secretaria de Estado de Pol\u00edcia Militar aplica hoje (5) na Uerj a prova de admiss\u00e3o para 133 vagas no Col\u00e9gio da Pol\u00edcia Militar, com 3.140 inscritos, em sua maioria dependentes de militares, disputando vagas no Ensino Fundamental Anos Finais e no Ensino M\u00e9dio. Do total de oportunidades, 75 vagas s\u00e3o para o 6\u00ba ano, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6889","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6889","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6889"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6889\/revisions"}],"predecessor-version":[{"id":6891,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6889\/revisions\/6891"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/6890"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6889"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6889"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6889"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}