{"id":6992,"date":"2025-10-15T18:21:09","date_gmt":"2025-10-15T21:21:09","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=6992"},"modified":"2025-10-15T18:21:09","modified_gmt":"2025-10-15T21:21:09","slug":"mae-relata-dores-abdominais-de-jovem-com-suspeita-de-intoxicacao-por-metanol-em-itapaci","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/10\/15\/mae-relata-dores-abdominais-de-jovem-com-suspeita-de-intoxicacao-por-metanol-em-itapaci\/","title":{"rendered":"M\u00e3e relata dores abdominais de jovem com suspeita de intoxica\u00e7\u00e3o por metanol em Itapaci"},"content":{"rendered":"<p>A m\u00e3e da jovem de 25 anos com suspeita de intoxica\u00e7\u00e3o por metanol afirmou que a filha apresentou dores no baixo ventre, no peito e nas costas antes de ser internada em estado grave na Unidade de Terapia Intensiva (UTI) do Hospital Estadual do Centro\u2011Norte Goiano (HCN), em Urua\u00e7u. Segundo a Secretaria Estadual de Sa\u00fade (SES), a paciente est\u00e1 entubada.<\/p>\n<p>De acordo com a m\u00e3e, a jovem deu entrada em um posto de sa\u00fade ap\u00f3s o in\u00edcio das dores, retornou para casa e apresentou piora do quadro: \u201cEla chegou em casa, j\u00e1 come\u00e7ou a vomitar o rem\u00e9dio que eles aplicaram nela\u201d, disse em entrevista \u00e0 TV Anhanguera. A fam\u00edlia reside em Itapaci.<\/p>\n<p>A SES informou que a paciente tem comorbidades, \u00e9 obesa e diab\u00e9tica, e que evoluiu de insufici\u00eancia respirat\u00f3ria para insufici\u00eancia renal desde a interna\u00e7\u00e3o. As autoridades seguem acompanhando o caso e aguardam resultados dos exames que confirmem ou descartem a presen\u00e7a de metanol.<\/p>\n<p>O delegado respons\u00e1vel pelo caso, F\u00e1bio Mendanha Castilho, confirmou que recipientes de bebida supostamente consumidos pela jovem foram identificados na resid\u00eancia da m\u00e3e, medida que integra as primeiras dilig\u00eancias investigativas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A m\u00e3e da jovem de 25 anos com suspeita de intoxica\u00e7\u00e3o por metanol afirmou que a filha apresentou dores no baixo ventre, no peito e nas costas antes de ser internada em estado grave na Unidade de Terapia Intensiva (UTI) do Hospital Estadual do Centro\u2011Norte Goiano (HCN), em Urua\u00e7u. Segundo a Secretaria Estadual de Sa\u00fade [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":6993,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-6992","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6992","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=6992"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6992\/revisions"}],"predecessor-version":[{"id":6994,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/6992\/revisions\/6994"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/6993"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=6992"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=6992"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=6992"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}