{"id":7003,"date":"2025-10-16T16:12:01","date_gmt":"2025-10-16T19:12:01","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=7003"},"modified":"2025-10-16T16:12:01","modified_gmt":"2025-10-16T19:12:01","slug":"fecomercio-encerra-temporada-com-quase-9-mil-atendimentos-no-gama","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/10\/16\/fecomercio-encerra-temporada-com-quase-9-mil-atendimentos-no-gama\/","title":{"rendered":"Fecom\u00e9rcio encerra temporada com quase 9 mil atendimentos no Gama"},"content":{"rendered":"<p>O projeto Fecom\u00e9rcio Mais Perto de Todos encerrou a temporada 2025 nos dias 3 e 4 de outubro no Gama, registrando 8.777 atendimentos e transformando a Pra\u00e7a 1, no Setor Central, em um polo de cidadania com servi\u00e7os de sa\u00fade, assist\u00eancia social, cultura, esporte e qualifica\u00e7\u00e3o profissional.<\/p>\n<p>Promovida pelo Sistema Fecom\u00e9rcio-DF \u2014 com lideran\u00e7a do presidente Jos\u00e9 Aparecido e execu\u00e7\u00e3o do Sesc-DF, Senac-DF e Instituto Fecom\u00e9rcio \u2014 a a\u00e7\u00e3o contou com apoio de parceiros como Caesb, Neoenergia, Defensoria P\u00fablica, Pol\u00edcia Civil do DF e Superintend\u00eancia Regional do Trabalho e Emprego, entre outros. A articula\u00e7\u00e3o entre setor empresarial e institui\u00e7\u00f5es p\u00fablicas ofertou \u00e0 popula\u00e7\u00e3o servi\u00e7os gratuitos que inclu\u00edram exames e triagens m\u00e9dicas, atendimentos odontol\u00f3gicos e oftalmol\u00f3gicos, coloca\u00e7\u00e3o de DIU, cortes de cabelo, oficinas gastron\u00f4micas, recupera\u00e7\u00e3o de bicicletas, a\u00e7\u00f5es de preven\u00e7\u00e3o a inc\u00eandio e programa\u00e7\u00e3o infantil.<\/p>\n<p>Um dos destaques da edi\u00e7\u00e3o foi a inaugura\u00e7\u00e3o da nova carreta OdontoSesc, equipada com tecnologia e ambiente climatizado para atendimento m\u00f3vel de sa\u00fade bucal, que ficar\u00e1 atendendo a comunidade at\u00e9 o fim do ano e em 2026. Jos\u00e9 Aparecido ressaltou que o projeto representa o investimento do empresariado devolvido em servi\u00e7os \u00e0 popula\u00e7\u00e3o e que a iniciativa cresce desde sua primeira edi\u00e7\u00e3o, realizada em 2021.<\/p>\n<p>Dirigentes do Sesc-DF e do Senac-DF destacaram o impacto social e a continuidade do projeto em 2026, apontando a combina\u00e7\u00e3o de servi\u00e7os, forma\u00e7\u00e3o profissional e inclus\u00e3o como elemento central do legado do Fecom\u00e9rcio Mais Perto de Todos. O encerramento tamb\u00e9m coincidiu com as comemora\u00e7\u00f5es dos 65 anos do Gama, celebradas com atividades que refor\u00e7aram a inclus\u00e3o social e o acesso a direitos b\u00e1sicos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O projeto Fecom\u00e9rcio Mais Perto de Todos encerrou a temporada 2025 nos dias 3 e 4 de outubro no Gama, registrando 8.777 atendimentos e transformando a Pra\u00e7a 1, no Setor Central, em um polo de cidadania com servi\u00e7os de sa\u00fade, assist\u00eancia social, cultura, esporte e qualifica\u00e7\u00e3o profissional. Promovida pelo Sistema Fecom\u00e9rcio-DF \u2014 com lideran\u00e7a do [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7004,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7003","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7003","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7003"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7003\/revisions"}],"predecessor-version":[{"id":7005,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7003\/revisions\/7005"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/7004"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7003"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7003"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7003"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}