{"id":7171,"date":"2025-10-31T13:25:54","date_gmt":"2025-10-31T16:25:54","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=7171"},"modified":"2025-10-31T13:25:54","modified_gmt":"2025-10-31T16:25:54","slug":"desemprego-fica-em-56-em-setembro-e-repete-minima-historica-aponta-ibge","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/10\/31\/desemprego-fica-em-56-em-setembro-e-repete-minima-historica-aponta-ibge\/","title":{"rendered":"Desemprego fica em 5,6% em setembro e repete m\u00ednima hist\u00f3rica, aponta IBGE"},"content":{"rendered":"<p>A taxa de desemprego no Brasil ficou em 5,6% no trimestre m\u00f3vel encerrado em setembro, informou o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) nesta sexta-feira. Foi o terceiro trimestre consecutivo no patamar de 5,6%, repetindo a m\u00ednima hist\u00f3rica da s\u00e9rie iniciada em 2012; no mesmo per\u00edodo de 2024, a taxa era de 6,4%.<\/p>\n<p>Ao todo, 6,045 milh\u00f5es de pessoas estavam desocupadas \u2014 o menor contingente j\u00e1 registrado na s\u00e9rie hist\u00f3rica \u2014, queda de 3,3% (209 mil pessoas) ante o trimestre anterior e de 11,8% (809 mil) na compara\u00e7\u00e3o anual. A popula\u00e7\u00e3o ocupada ficou est\u00e1vel em 102,4 milh\u00f5es, recorde hist\u00f3rico, com aumento de 1,4% no ano (mais 1,4 milh\u00e3o de pessoas).<\/p>\n<p>O n\u00edvel de ocupa\u00e7\u00e3o atingiu 58,7%, est\u00e1vel frente ao trimestre anterior e 0,3 ponto percentual acima do registrado h\u00e1 12 meses. A popula\u00e7\u00e3o fora da for\u00e7a de trabalho somou 65,9 milh\u00f5es, enquanto a popula\u00e7\u00e3o desalentada foi de 2,6 milh\u00f5es.<\/p>\n<p>Formaliza\u00e7\u00e3o e composi\u00e7\u00e3o do emprego O setor privado empregou 52,7 milh\u00f5es de trabalhadores \u2014 o maior contingente da s\u00e9rie. Os empregados com carteira assinada (excluindo dom\u00e9sticos) chegaram a 39,2 milh\u00f5es, novo recorde do IBGE, com alta anual de 2,7% (mais 1 milh\u00e3o). Os empregados sem carteira somaram 13,5 milh\u00f5es, est\u00e1veis no trimestre e 4,0% abaixo do ano anterior.<\/p>\n<p>A informalidade alcan\u00e7ou 37,8% da popula\u00e7\u00e3o ocupada (38,7 milh\u00f5es), n\u00edvel est\u00e1vel no trimestre e levemente inferior ao de setembro de 2024 (38,8%). Entre os informais, os trabalhadores por conta pr\u00f3pria totalizaram 25,9 milh\u00f5es, com crescimento anual de 4,1% (mais 1 milh\u00e3o).<\/p>\n<p>Setores com alta e queda na ocupa\u00e7\u00e3o Dois dos dez grupos de atividade registraram expans\u00e3o no trimestre: agropecu\u00e1ria e pesca (+3,4%, mais 260 mil) e constru\u00e7\u00e3o (+3,4%, mais 249 mil). Houve retra\u00e7\u00e3o no com\u00e9rcio e repara\u00e7\u00e3o de ve\u00edculos (-1,4%, menos 274 mil) e em servi\u00e7os dom\u00e9sticos (-2,9%, menos 165 mil). Na compara\u00e7\u00e3o anual, destaque para transporte, armazenagem e correio (+6,7%, mais 371 mil) e para administra\u00e7\u00e3o p\u00fablica, educa\u00e7\u00e3o e sa\u00fade (+3,9%, mais 724 mil); servi\u00e7os dom\u00e9sticos recuou 5,1% (menos 301 mil).<\/p>\n<p>Rendimento e massa salarial em m\u00e1ximas hist\u00f3ricas O rendimento m\u00e9dio real habitual atingiu R$ 3.507, maior valor da s\u00e9rie, est\u00e1vel no trimestre e 4,0% acima do ano anterior. A massa de rendimento real totalizou R$ 354,6 bilh\u00f5es, recorde hist\u00f3rico, com alta anual de 5,5% (R$ 18,5 bilh\u00f5es a mais).<\/p>\n<p>Avalia\u00e7\u00e3o do IBGE Para Adriana Beringuy, coordenadora de pesquisas domiciliares do IBGE, o elevado n\u00edvel de ocupa\u00e7\u00e3o nos \u00faltimos meses indica que a retra\u00e7\u00e3o do desemprego ao longo de 2025 mostra sinais de sustentabilidade.<\/p>\n<p>Principais indicadores do trimestre encerrado em setembro: taxa de desocupa\u00e7\u00e3o 5,6%; subutiliza\u00e7\u00e3o 13,9%; popula\u00e7\u00e3o ocupada 102,4 milh\u00f5es; popula\u00e7\u00e3o desocupada 6,045 milh\u00f5es; empregados com carteira 39,2 milh\u00f5es; trabalhadores informais 38,7 milh\u00f5es.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A taxa de desemprego no Brasil ficou em 5,6% no trimestre m\u00f3vel encerrado em setembro, informou o Instituto Brasileiro de Geografia e Estat\u00edstica (IBGE) nesta sexta-feira. Foi o terceiro trimestre consecutivo no patamar de 5,6%, repetindo a m\u00ednima hist\u00f3rica da s\u00e9rie iniciada em 2012; no mesmo per\u00edodo de 2024, a taxa era de 6,4%. Ao [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7172,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[5],"tags":[],"class_list":["post-7171","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7171","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7171"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7171\/revisions"}],"predecessor-version":[{"id":7173,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7171\/revisions\/7173"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/7172"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7171"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7171"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7171"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}