{"id":7419,"date":"2025-12-05T13:31:22","date_gmt":"2025-12-05T16:31:22","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=7419"},"modified":"2025-12-05T13:31:22","modified_gmt":"2025-12-05T16:31:22","slug":"luziania-abre-matriculas-da-eja-e-passa-a-oferecer-6o-ano","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/12\/05\/luziania-abre-matriculas-da-eja-e-passa-a-oferecer-6o-ano\/","title":{"rendered":"Luzi\u00e2nia abre matr\u00edculas da EJA e passa a oferecer 6\u00ba ano"},"content":{"rendered":"<p>Em v\u00eddeo divulgado nas redes sociais, o prefeito <strong>Diego Sorgatto<\/strong> anunciou a abertura das matr\u00edculas para a <strong>Educa\u00e7\u00e3o de Jovens e Adultos (EJA)<\/strong> da rede municipal de Luzi\u00e2nia e informou a principal novidade desta edi\u00e7\u00e3o: a oferta do <strong>sexto ano<\/strong> da EJA, ampliando o acesso ao ensino b\u00e1sico para jovens, adultos e idosos. \u201cSe voc\u00ea \u00e9 jovem, adulto ou at\u00e9 mesmo idoso, esse \u00e9 o momento para retomar os seus estudos e abrir novas portas na sua vida\u201d, afirmou o prefeito.<\/p>\n<p>As inscri\u00e7\u00f5es est\u00e3o sendo realizadas em duas unidades: <strong>Escola Dona Geni<\/strong>, no Distrito Jardim Ing\u00e1, e <strong>Escola Ana Reis Meirelles (CREJA)<\/strong>, no centro da cidade. Ambas funcionam nos <strong>tr\u00eas turnos<\/strong> e contam com <strong>transporte escolar<\/strong> para facilitar a frequ\u00eancia dos alunos. Durante o an\u00fancio, Sorgatto convidou os moradores a procurarem as unidades para garantir a matr\u00edcula e pediu que compartilhem a informa\u00e7\u00e3o com quem deseja voltar a estudar.<\/p>\n<p>A amplia\u00e7\u00e3o da EJA com a inclus\u00e3o do sexto ano representa, segundo a prefeitura, um passo importante para garantir <strong>educa\u00e7\u00e3o de qualidade<\/strong> e ampliar oportunidades. \u201cA educa\u00e7\u00e3o muda vidas e a Prefeitura de Luzi\u00e2nia est\u00e1 aqui para caminhar com voc\u00ea\u201d, declarou o prefeito, ressaltando o compromisso do munic\u00edpio em oferecer condi\u00e7\u00f5es para que a popula\u00e7\u00e3o retome a forma\u00e7\u00e3o com dignidade e apoio.<\/p>\n<p>A iniciativa integra a pol\u00edtica municipal de inclus\u00e3o educacional e busca atender demandas de quem n\u00e3o concluiu o ensino fundamental na idade regular, oferecendo alternativas de forma\u00e7\u00e3o e reinser\u00e7\u00e3o escolar.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em v\u00eddeo divulgado nas redes sociais, o prefeito Diego Sorgatto anunciou a abertura das matr\u00edculas para a Educa\u00e7\u00e3o de Jovens e Adultos (EJA) da rede municipal de Luzi\u00e2nia e informou a principal novidade desta edi\u00e7\u00e3o: a oferta do sexto ano da EJA, ampliando o acesso ao ensino b\u00e1sico para jovens, adultos e idosos. \u201cSe voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7420,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[31],"tags":[],"class_list":["post-7419","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-luziania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7419"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7419\/revisions"}],"predecessor-version":[{"id":7421,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7419\/revisions\/7421"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/7420"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}