{"id":7491,"date":"2025-12-05T14:31:03","date_gmt":"2025-12-05T17:31:03","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=7491"},"modified":"2025-12-05T14:31:03","modified_gmt":"2025-12-05T17:31:03","slug":"procon-goiania-lista-precos-e-pacotes-pagos-para-reveillon-na-capital","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2025\/12\/05\/procon-goiania-lista-precos-e-pacotes-pagos-para-reveillon-na-capital\/","title":{"rendered":"Procon Goi\u00e2nia lista pre\u00e7os e pacotes pagos para R\u00e9veillon na capital"},"content":{"rendered":"<p>O <strong>Procon Goi\u00e2nia<\/strong> divulgou nesta semana uma pesquisa com dez estabelecimentos que oferecem programa\u00e7\u00e3o paga para a noite de R\u00e9veillon, reunindo op\u00e7\u00f5es entre bares, restaurantes, casas de festa e hot\u00e9is com pacotes que variam conforme localiza\u00e7\u00e3o, estrutura, atra\u00e7\u00f5es musicais, ceias especiais, open bar e possibilidade de reserva de mesas ou camarotes.<\/p>\n<p>Entre os valores levantados est\u00e3o pacotes do <strong>Velho Texas \u2013 Steak and Drinks<\/strong> entre <strong>R$ 1.600<\/strong> e <strong>R$ 6.000<\/strong>, op\u00e7\u00f5es do <strong>Coco Bambu<\/strong> de <strong>R$ 250<\/strong> a <strong>R$ 600<\/strong>, rod\u00edzio especial do <strong>JP Steak House<\/strong> por <strong>R$ 279,90<\/strong> por pessoa, entradas na <strong>Cerrado Cervejaria<\/strong> a <strong>R$ 240<\/strong> (mulheres) e <strong>R$ 290<\/strong> (homens) e ingressos da <strong>Cervejaria Dias<\/strong> a partir de <strong>R$ 399,90<\/strong> no 1\u00ba lote; ceias tradicionais aparecem na pesquisa, como a <strong>Churrascaria Gramado<\/strong> por <strong>R$ 169,90<\/strong> e a <strong>Nativas Grill<\/strong> por <strong>R$ 319<\/strong>, enquanto a <strong>Churrascaria Favo de Mel<\/strong> cobra <strong>R$ 319,90<\/strong> no sal\u00e3o principal e <strong>R$ 349<\/strong> no sal\u00e3o superior, e o <strong>Castro\u2019s Park Hotel<\/strong> oferece pacote com hospedagem \u201cVintage Circus\u201d por <strong>R$ 2.897,22<\/strong> para dois adultos, incluindo di\u00e1ria entre 31\/12 e 1\u00ba\/1 e estacionamento cortesia. O Procon orienta consumidores a checar antecipadamente o que est\u00e1 inclu\u00eddo no pacote \u2014 alimenta\u00e7\u00e3o, bebidas, atra\u00e7\u00f5es, hor\u00e1rios, pol\u00edtica de cancelamento e taxas adicionais \u2014, exigir comprovante de compra e ler o regulamento do evento para evitar surpresas na virada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Procon Goi\u00e2nia divulgou nesta semana uma pesquisa com dez estabelecimentos que oferecem programa\u00e7\u00e3o paga para a noite de R\u00e9veillon, reunindo op\u00e7\u00f5es entre bares, restaurantes, casas de festa e hot\u00e9is com pacotes que variam conforme localiza\u00e7\u00e3o, estrutura, atra\u00e7\u00f5es musicais, ceias especiais, open bar e possibilidade de reserva de mesas ou camarotes. Entre os valores levantados [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":7492,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[29],"tags":[],"class_list":["post-7491","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-goiania","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=7491"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7491\/revisions"}],"predecessor-version":[{"id":7493,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/7491\/revisions\/7493"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/7492"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=7491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=7491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=7491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}