{"id":863,"date":"2023-08-08T14:48:13","date_gmt":"2023-08-08T17:48:13","guid":{"rendered":"https:\/\/entorno24h.com.br\/?p=863"},"modified":"2023-08-08T14:48:13","modified_gmt":"2023-08-08T17:48:13","slug":"goias-e-minas-gerais-unem-forcas-em-plano-para-preservar-especies-ameacadas","status":"publish","type":"post","link":"https:\/\/entorno24h.com.br\/index.php\/2023\/08\/08\/goias-e-minas-gerais-unem-forcas-em-plano-para-preservar-especies-ameacadas\/","title":{"rendered":"&#8220;Goi\u00e1s e Minas Gerais Unem For\u00e7as em Plano para Preservar Esp\u00e9cies Amea\u00e7adas&#8221;"},"content":{"rendered":"<p>Os governos de Goi\u00e1s e Minas Gerais est\u00e3o lan\u00e7ando um Plano de A\u00e7\u00e3o Territorial (PAT) com o prop\u00f3sito de preservar nove esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o que foram registradas em algum momento nos dois estados. Entre as esp\u00e9cies alvo est\u00e3o tr\u00eas tipos de peixe, quatro esp\u00e9cies de plantas, um invertebrado e um mam\u00edfero.<\/p>\n<p>As a\u00e7\u00f5es planejadas ser\u00e3o implementadas em 18 munic\u00edpios goianos e 15 mineiros, com coordena\u00e7\u00e3o dos respectivos \u00f3rg\u00e3os ambientais estaduais. A Secretaria de Meio Ambiente e Desenvolvimento Sustent\u00e1vel (Semad) ficar\u00e1 respons\u00e1vel pela coordena\u00e7\u00e3o em Goi\u00e1s.<\/p>\n<p>O PAT visa proteger esp\u00e9cies valiosas da flora e fauna, incluindo plantas como Diplusodon panniculatus e Jacaranda intricata, bem como peixes como Hypsolebias virgulatus e Simpsonichthys zonatus. O plano tamb\u00e9m engloba a\u00e7\u00f5es espec\u00edficas para o invertebrado Plesiophysa dolichomastix e o mam\u00edfero Juscelinomys candango.<\/p>\n<p>O PAT tra\u00e7a um plano com 25 a\u00e7\u00f5es organizadas em tr\u00eas grupos de objetivos. Estas a\u00e7\u00f5es visam mapear \u00e1reas de ocorr\u00eancia das esp\u00e9cies, coletar germoplasma, estudar variabilidade gen\u00e9tica, promover a cria\u00e7\u00e3o de unidades de conserva\u00e7\u00e3o municipais e incentivar projetos de Pagamento por Servi\u00e7o Ambiental (PSA). O foco \u00e9 neutralizar os riscos \u00e0 preserva\u00e7\u00e3o das esp\u00e9cies, incluindo desmatamento, rebaixamento do len\u00e7ol fre\u00e1tico, queimadas e polui\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m das esp\u00e9cies-alvo, cerca de 89 outras esp\u00e9cies tamb\u00e9m devem se beneficiar com a execu\u00e7\u00e3o desse plano. O PAT recebeu o nome de Veredas Goyaz-Geraes em homenagem ao livro &#8220;Grande Sert\u00e3o: Veredas&#8221; de Guimar\u00e3es Rosa, inspirado nas caracter\u00edsticas das veredas, t\u00edpicas do Cerrado, que s\u00e3o alagadas e sinuosas como os caminhos estreitos descritos na obra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os governos de Goi\u00e1s e Minas Gerais est\u00e3o lan\u00e7ando um Plano de A\u00e7\u00e3o Territorial (PAT) com o prop\u00f3sito de preservar nove esp\u00e9cies amea\u00e7adas de extin\u00e7\u00e3o que foram registradas em algum momento nos dois estados. Entre as esp\u00e9cies alvo est\u00e3o tr\u00eas tipos de peixe, quatro esp\u00e9cies de plantas, um invertebrado e um mam\u00edfero. As a\u00e7\u00f5es planejadas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":864,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","omw_enable_modal_window":"enable","_joinchat":[],"ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[],"footnotes":""},"categories":[21,5],"tags":[],"class_list":["post-863","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-governo","category-ultimasnoticias","entry","has-media"],"_links":{"self":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/863","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=863"}],"version-history":[{"count":1,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/863\/revisions"}],"predecessor-version":[{"id":865,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/posts\/863\/revisions\/865"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media\/864"}],"wp:attachment":[{"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/entorno24h.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}